{"id":3776,"date":"2019-01-16T22:30:31","date_gmt":"2019-01-16T22:30:31","guid":{"rendered":"http:\/\/coolcasc.com\/?page_id=3776"},"modified":"2025-01-16T15:50:50","modified_gmt":"2025-01-16T15:50:50","slug":"notre-histoire","status":"publish","type":"page","link":"https:\/\/coolcasc.com\/fr\/notre-histoire\/","title":{"rendered":"Notre Histoire"},"content":{"rendered":"\n<div class=\"row align-center\"  id=\"row-1854979692\">\n\n\n\t<div id=\"col-101698489\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"height:10px;\"><\/div><\/div>\n\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" >2007<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n\n<p style=\"text-align: center;\"><strong>Coolcasc\u00ae<\/strong>, na\u00eet dans un petit restaurant des Alpes Suisses \u201cAuxvieuxVerbier\u201d pendant des vacances de ski, en mars 2007.<\/p>\n<p style=\"text-align: center;\">Mar Peire, voulait trouver la mani\u00e8re de diff\u00e9rencier ses enfants sur les pistes de ski. C\u2019\u00e9tait clair ! Se mettre quelque chose sur le casque, qui lui donnerait un aspect amusant qui plairait aux enfants et qui permettait de les identifier rapidement pendant qu\u2019ils skient.<\/p>\n<p style=\"text-align: center;\">Ainsi sont n\u00e9es les housses pour casque COOLCASC\u00ae. Il n\u2019existe rien de similaire sur le march\u00e9, et avant la fin de l\u2019ann\u00e9e, nous avons d\u00e9pos\u00e9 le brevet et les designs.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-101698489 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 0px 0px -30px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row align-center\"  id=\"row-2051106997\">\n\n\n\t<div id=\"col-1784635340\" class=\"col medium-9 small-12 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1246315363\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:54%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"422\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Paginas\/2007.jpg\" class=\"attachment-large size-large\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1246315363 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row align-center\"  id=\"row-963736316\">\n\n\n\t<div id=\"col-1945952667\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" >2008<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n\n<p style=\"text-align: center;\">Une ann\u00e9e apr\u00e8s arrivent les premiers mod\u00e8les. Notre <a href=\"http:\/\/coolcasc-tienda.com\/epages\/ec1588.sf\/es_ES\/?ObjectPath=\/Shops\/ec1588\/Products\/041\">dinosaure<\/a> et le petit cochon.<\/p>\n<p style=\"text-align: center;\"Nous concevons et brevetons notre \u201cpackaging\u201d exclusif<\/p>\n<p style=\"text-align: center;\">Comme autant d\u2019autres soci\u00e9t\u00e9s, nous avons commenc\u00e9 dans un garage, o\u00f9 nous avons compl\u00e9t\u00e9 nos premi\u00e8res commandes.<\/p>\n<p style=\"text-align: center;\">Nous ouvrons notre<a href=\"http:\/\/coolcasc-tienda.com\/\"> magasin on-line<\/a>.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1945952667 > .col-inner {\n  margin: 0px 0px -30px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\n<style>\n#row-963736316 > .col > .col-inner {\n  padding: 60px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n<div class=\"row align-center\"  id=\"row-123354734\">\n\n\n\t<div id=\"col-1653427918\" class=\"col medium-9 small-12 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1547391318\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:54%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"422\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Paginas\/2008.jpg\" class=\"attachment-large size-large\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1547391318 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1653427918 > .col-inner {\n  padding: 0px 0px 1px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row align-center\"  id=\"row-900818954\">\n\n\n\t<div id=\"col-565359163\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" >2009<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n\n<p style=\"text-align: center;\">Nous engageons nos premiers repr\u00e9sentants et nous commen\u00e7ons \u00e0 esquisser notre r\u00e9seau de distribution nationale.\/p><\/p>\n<p style=\"text-align: center;\">Nous apparaissons dans la presse.<\/p>\n<p style=\"text-align: center;\">Notre produit plait et amuse. Nous sommes d\u00e9j\u00e0 connus sur les pistes de ski !<\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-565359163 > .col-inner {\n  margin: 0px 0px -30px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\n<style>\n#row-900818954 > .col > .col-inner {\n  padding: 56px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n<div class=\"row align-center\"  id=\"row-1105663426\">\n\n\n\t<div id=\"col-776137570\" class=\"col medium-9 small-12 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2007497327\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:54%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"422\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Paginas\/2009.jpg\" class=\"attachment-original size-original\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2007497327 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-776137570 > .col-inner {\n  padding: 0px 0px 1px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row align-center\"  id=\"row-585783430\">\n\n\n\t<div id=\"col-1959533436\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" >2010<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n\n<p style=\"text-align: center;\">ous d\u00e9veloppons notre catalogue jusqu\u2019\u00e0 pratiquement 50 r\u00e9f\u00e9rences diff\u00e9rentes et nous pr\u00e9sentons la collection Estampados Cool.<\/p>\n<p style=\"text-align: center;\">Nous commen\u00e7ons la commercialisation \u00e0 El Corte Ingl\u00e9s.<\/p>\n<p style=\"text-align: center;\"><strong>Nous ouvrons nos bureaux \u00e0 Madrid.<\/strong><\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\n<style>\n#row-585783430 > .col > .col-inner {\n  padding: 56px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n<div class=\"row align-center\"  id=\"row-1923641351\">\n\n\n\t<div id=\"col-497194555\" class=\"col medium-9 small-12 large-9\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1511437356\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:54%;margin:-23px 0px 0px 0px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"422\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Paginas\/2010.jpg\" class=\"attachment-large size-large\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1511437356 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row align-center\"  id=\"row-1427514101\">\n\n\n\t<div id=\"col-121629803\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" >2012<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n\n<p style=\"text-align: center;\">Nous sommes enfin pr\u00eats \u00e0 commencer notre internationalisation.<\/p>\n<p style=\"text-align: center;\">\u00c0 ISPO 2012 commence notre aventure internationale.<\/p>\n<p style=\"text-align: center;\">Acceptation et reconnaissance loin de chez nous.<\/p>\n<p style=\"text-align: center;\">Nous ouvrons de nouveaux march\u00e9s en France, Autriche et Italie.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-121629803 > .col-inner {\n  margin: 0px 0px -30px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\n<style>\n#row-1427514101 > .col > .col-inner {\n  padding: 56px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n<div class=\"row align-center\"  id=\"row-664554533\">\n\n\n\t<div id=\"col-1378031614\" class=\"col medium-9 small-12 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1020804099\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:54%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"422\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Paginas\/2012.jpg\" class=\"attachment-large size-large\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1020804099 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1378031614 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\n<style>\n#row-664554533 > .col > .col-inner {\n  padding: 56px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n<div class=\"row align-center\"  id=\"row-1444899991\">\n\n\n\t<div id=\"col-1818770923\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"container section-title-container\" style=\"margin-top:40px;\"><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" >2014<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n\n<p style=\"text-align: center;\">Notre r\u00e9seau de distribution internationale continue \u00e0 se d\u00e9velopper.<\/p>\n<p style=\"text-align: center;\">Nous diversifions notre march\u00e9 cible \u00e0 d\u2019autres secteurs sportifs \u00e0 part le ski, comme le cyclisme, le patinage, etc. COOLCASC\u00ae sert \u00e0 tout casque, quel que soit le sport.<\/strong><\/p>\n<p style=\"text-align: center;\">Nous d\u00e9veloppons une offre vari\u00e9e de housses customis\u00e9es et personnalisables.<\/p>\n<p style=\"text-align: center;\">Nous pr\u00e9sentons une collection exclusive pour le v\u00e9lo.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1818770923 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 0px 0px -48px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\n<style>\n#row-1444899991 > .col > .col-inner {\n  padding: 60px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n<div class=\"row align-center\"  id=\"row-1802916360\">\n\n\n\t<div id=\"col-575070200\" class=\"col medium-9 small-12 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1721700153\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:54%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"422\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Paginas\/2014.jpg\" class=\"attachment-large size-large\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1721700153 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-575070200 > .col-inner {\n  margin: -30px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\n<style>\n#row-1802916360 > .col > .col-inner {\n  padding: 56px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n<div class=\"row align-center\"  id=\"row-236343963\">\n\n\n\t<div id=\"col-651368726\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" >2016<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n\n<p style=\"text-align: center;\">Nous nous positionnons comme marque <strong># 1 des couvre casques<\/STRONG>.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\n<style>\n#row-236343963 > .col > .col-inner {\n  padding: 67px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n<div class=\"row align-center\"  id=\"row-307352454\">\n\n\n\t<div id=\"col-2133047887\" class=\"col medium-9 small-12 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1585747861\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:54%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"749\" height=\"405\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Paginas\/2016.jpg\" class=\"attachment-large size-large\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1585747861 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2133047887 > .col-inner {\n  margin: -23px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row align-center\"  id=\"row-575656508\">\n\n\n\t<div id=\"col-850048304\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" >2018<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n\n<p style=\"text-align: center;\">Nous consolidons notre marque de housses de casque sur le plan international avec une pr\u00e9sence dans plus de 30 pays.<\/p>\n<p style=\"text-align: center;\">Nous c\u00e9l\u00e9brons nos 10 premi\u00e8res ann\u00e9es de succ\u00e8s sur le march\u00e9.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-850048304 > .col-inner {\n  margin: 0px 0px -20px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\n<style>\n#row-575656508 > .col > .col-inner {\n  padding: 60px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n<div class=\"row align-center\"  id=\"row-1305845117\">\n\n\n\t<div id=\"col-240272893\" class=\"col medium-9 small-12 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_392126499\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:54%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"422\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Paginas\/2018.jpg\" class=\"attachment-large size-large\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_392126499 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-240272893 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row align-center\"  id=\"row-1223830447\">\n\n\n\t<div id=\"col-1386562185\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" >2020<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n\n<p>Lors de l&rsquo;ISPO 2020, nous avons lanc\u00e9 un nouveau produit : les housses pour masques de ski COOLMASC. En utilisant le m\u00eame savoir-faire et les m\u00eames techniques d&rsquo;impression, mais avec un nouveau tissu en lycra fabriqu\u00e9 \u00e0 partir de bouteilles en plastique recycl\u00e9es. Une toute nouvelle collection assortie \u00e0 nos housses de casque a \u00e9t\u00e9 pr\u00e9sent\u00e9e \u00e0 Munich.<\/p>\n<p>Seulement un mois plus tard, la pand\u00e9mie a commenc\u00e9 et nous avons d\u00fb nous r\u00e9inventer, ainsi qu&rsquo;une partie de l&rsquo;entreprise, pendant le confinement. Nous devons maintenant pers\u00e9v\u00e9rer dans ce qui a \u00e9t\u00e9 accompli et essayer d&rsquo;aller encore plus loin. Il suffit de continuer, tout en profitant toujours du voyage.<\/p>\n<p>\u00a0<\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1386562185 > .col-inner {\n  margin: 0px 0px -20px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\n<style>\n#row-1223830447 > .col > .col-inner {\n  padding: 60px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n<div class=\"row align-center\"  id=\"row-1838733278\">\n\n\n\t<div id=\"col-491486007\" class=\"col medium-9 small-12 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2083203547\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:54%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"422\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/2021\/01\/2020.jpg\" class=\"attachment-large size-large\" alt=\"2020\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2083203547 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-491486007 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row align-center\"  id=\"row-456468801\">\n\n\n\t<div id=\"col-689753810\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" >2024<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n\n<p>Les ann\u00e9es de la pand\u00e9mie ont \u00e9t\u00e9 compliqu\u00e9es, tr\u00e8s compliqu\u00e9es, mais avec la r\u00e9ouverture des stations de ski, nous avons entam\u00e9 le chemin de la reprise.<\/p>\n<p>En janvier 2024, nous avons r\u00e9alis\u00e9 que nos installations \u00e0 Madrid \u00e9taient devenues trop petites et avons vu la n\u00e9cessit\u00e9 de regrouper bureaux et entrep\u00f4t pour une gestion plus efficace et un meilleur service \u00e0 nos clients.<\/p>\n<p>En mai 2024, nous avons fait un grand pas en avant en d\u00e9m\u00e9nageant dans un entrep\u00f4t industriel \u00e0 deux \u00e9tages situ\u00e9 dans la zone industrielle Eur\u00f3polis \u00e0 Las Rozas, Madrid. Nous disposons d\u00e9sormais d\u2019un entrep\u00f4t adapt\u00e9 au rez-de-chauss\u00e9e et de bureaux \u00e0 l\u2019\u00e9tage sup\u00e9rieur. Ces nouvelles installations nous offrent les conditions n\u00e9cessaires pour continuer \u00e0 cro\u00eetre et offrir le meilleur service \u00e0 nos clients.<\/p>\n<p>\u00a0<\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-689753810 > .col-inner {\n  margin: 0px 0px -20px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\n<style>\n#row-456468801 > .col > .col-inner {\n  padding: 60px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n<div class=\"row align-center\"  id=\"row-1819365107\">\n\n\n\t<div id=\"col-124628129\" class=\"col medium-9 small-12 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1474994156\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:54%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"480\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/2025\/01\/2-1.jpg\" class=\"attachment-large size-large\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1474994156 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-124628129 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row align-center\"  id=\"row-856615049\">\n\n\n\t<div id=\"col-529130683\" class=\"col medium-9 small-12 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"uxb-no-content uxb-image\">Upload Image...<\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-529130683 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank-title-center.php","meta":{"footnotes":""},"class_list":["post-3776","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Notre Histoire - Coolcasc<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coolcasc.com\/fr\/notre-histoire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Notre Histoire - Coolcasc\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coolcasc.com\/fr\/notre-histoire\/\" \/>\n<meta property=\"og:site_name\" content=\"Coolcasc\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/COOLCASC\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-16T15:50:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@coolcasc\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/notre-histoire\\\/\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/notre-histoire\\\/\",\"name\":\"Notre Histoire - Coolcasc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#website\"},\"datePublished\":\"2019-01-16T22:30:31+00:00\",\"dateModified\":\"2025-01-16T15:50:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/notre-histoire\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/coolcasc.com\\\/fr\\\/notre-histoire\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/notre-histoire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Notre Histoire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#website\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/\",\"name\":\"Coolcasc\",\"description\":\"Seguridad, moda y dise\u00f1o utilizando las fundas para casco Coolcasc en la pr\u00e1ctica de cualquier deporte.\",\"publisher\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/coolcasc.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#organization\",\"name\":\"Fundas para cascos Coolcasc\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Blue_header.png\",\"contentUrl\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Blue_header.png\",\"width\":300,\"height\":180,\"caption\":\"Fundas para cascos Coolcasc\"},\"image\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/COOLCASC\\\/\",\"https:\\\/\\\/x.com\\\/coolcasc\",\"https:\\\/\\\/www.instagram.com\\\/coolcasc\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Notre Histoire - Coolcasc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coolcasc.com\/fr\/notre-histoire\/","og_locale":"fr_FR","og_type":"article","og_title":"Notre Histoire - Coolcasc","og_url":"https:\/\/coolcasc.com\/fr\/notre-histoire\/","og_site_name":"Coolcasc","article_publisher":"https:\/\/www.facebook.com\/COOLCASC\/","article_modified_time":"2025-01-16T15:50:50+00:00","twitter_card":"summary_large_image","twitter_site":"@coolcasc","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coolcasc.com\/fr\/notre-histoire\/","url":"https:\/\/coolcasc.com\/fr\/notre-histoire\/","name":"Notre Histoire - Coolcasc","isPartOf":{"@id":"https:\/\/coolcasc.com\/#website"},"datePublished":"2019-01-16T22:30:31+00:00","dateModified":"2025-01-16T15:50:50+00:00","breadcrumb":{"@id":"https:\/\/coolcasc.com\/fr\/notre-histoire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coolcasc.com\/fr\/notre-histoire\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/coolcasc.com\/fr\/notre-histoire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/coolcasc.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Notre Histoire"}]},{"@type":"WebSite","@id":"https:\/\/coolcasc.com\/#website","url":"https:\/\/coolcasc.com\/","name":"Coolcasc","description":"Seguridad, moda y dise\u00f1o utilizando las fundas para casco Coolcasc en la pr\u00e1ctica de cualquier deporte.","publisher":{"@id":"https:\/\/coolcasc.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coolcasc.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/coolcasc.com\/#organization","name":"Fundas para cascos Coolcasc","url":"https:\/\/coolcasc.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/coolcasc.com\/#\/schema\/logo\/image\/","url":"https:\/\/coolcasc.com\/wp-content\/uploads\/2018\/12\/Blue_header.png","contentUrl":"https:\/\/coolcasc.com\/wp-content\/uploads\/2018\/12\/Blue_header.png","width":300,"height":180,"caption":"Fundas para cascos Coolcasc"},"image":{"@id":"https:\/\/coolcasc.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/COOLCASC\/","https:\/\/x.com\/coolcasc","https:\/\/www.instagram.com\/coolcasc\/"]}]}},"_links":{"self":[{"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/pages\/3776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/comments?post=3776"}],"version-history":[{"count":2,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/pages\/3776\/revisions"}],"predecessor-version":[{"id":25373,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/pages\/3776\/revisions\/25373"}],"wp:attachment":[{"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/media?parent=3776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}