{"id":10403,"date":"2019-09-28T23:14:11","date_gmt":"2019-09-28T23:14:11","guid":{"rendered":"https:\/\/coolcasc.com\/?post_type=product&#038;p=10403"},"modified":"2024-11-29T10:16:41","modified_gmt":"2024-11-29T10:16:41","slug":"oiseau","status":"publish","type":"product","link":"https:\/\/coolcasc.com\/fr\/Housses de casque\/oiseau\/","title":{"rendered":"Oiseau"},"content":{"rendered":"<div class=\"row row-collapse row-full-width\"  id=\"row-147747812\">\n\n\t<div id=\"col-1323050235\" class=\"col medium-6 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center dark\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1952229823\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:0px 10px 0 10px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"505\" height=\"505\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/2019\/09\/Pajaro-1.jpg\" class=\"attachment-original size-original\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1952229823 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1363608869\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:0px 10px 0 10px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"505\" height=\"505\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/2019\/09\/Pajaro-3.jpg\" class=\"attachment-original size-original\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1363608869 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1429302978\" class=\"col medium-6 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1824555148\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:0px 10px 0 10px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"505\" height=\"505\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/2019\/09\/Pajaro-2.jpg\" class=\"attachment-original size-original\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1824555148 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_945147875\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:0px 10px 0 10px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"505\" height=\"505\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/2019\/09\/Pajaro-4.jpg\" class=\"attachment-original size-original\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_945147875 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-147747812 > .col > .col-inner {\n  padding: 0px 0px 15px 0px;\n}\n<\/style>\n<\/div>\n<div class=\"container section-title-container\" style=\"margin-bottom:0px;\"><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" style=\"font-size:92%;\">POURQUOI METTRE UN COOLCASC \u00c0 MON CASQUE?<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n<div class=\"row row-small\"  id=\"row-1441765004\">\n\n\t<div id=\"col-52303736\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<ul>\n<li style=\"text-align: left;\">Parce que je peux rapidement renouveler l&rsquo;aspect de mon casque..<\/li>\n<li style=\"text-align: left;\">Parce que je change de style quand je veux.<\/li>\n<li style=\"text-align: left;\">Parce qu&rsquo;il me pla\u00eet de diff\u00e9rer du reste.<\/li>\n<li style=\"text-align: left;\">Parce que je prot\u00e8ge mon casque des rayures.<\/li>\n<\/ul>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-52303736 > .col-inner {\n  margin: -35px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1347748502\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_935622940\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:-5px 0px 0px 0px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"505\" height=\"505\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Colecciones\/Animales\/P\u00e1jaro-F.jpg\" class=\"attachment-original size-original\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_935622940 {\n  width: 80%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1347748502 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 0px 0px -17px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1250570871\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<ul>\n<li style=\"text-align: left;\">Parce que je peux l\u00b4utiliser toute l&rsquo;ann\u00e9e, pour n&rsquo;importe quel casque et dans n&rsquo;importe quel sport.<\/li>\n<li style=\"text-align: left;\">Parce qu&rsquo;il me pla\u00eet de mettre une touche de couleur et d&rsquo;humour\u00a0 \u00e0 ma vie.<\/li>\n<li style=\"text-align: left;\">Parce qu&rsquo;\u00e0 je suis plus visible donc je vais beaucoup plus s\u00fbr.<\/li>\n<\/ul>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1250570871 > .col-inner {\n  margin: -35px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-1441765004 > .col > .col-inner {\n  padding: 55px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n\n  <div class=\"banner has-hover\" id=\"banner-280345127\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"1050\" height=\"702\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Colecciones\/Animales\/Live\/P\u00e1jaro-G.jpg\" class=\"bg attachment-original size-original\" alt=\"Funda casco P\u00e1jaro monopat\u00edn G\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1021529724\" class=\"text-box banner-layer x5 md-x5 lg-x5 y5 md-y5 lg-y5 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-left\">\n                  \n<h2 class=\"uppercase\"><strong>Oiseau<\/strong><\/h2>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1021529724 {\n  width: 60%;\n}\n#text-box-1021529724 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-1021529724 {\n    width: 32%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-280345127 {\n  padding-top: 61%;\n}\n#banner-280345127 .banner-bg img {\n  object-position: 52% 15%;\n}\n<\/style>\n  <\/div>\n\n\n<div class=\"row\"  id=\"row-522693118\">\n\n\t<div id=\"col-1234895110\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container\" style=\"margin-bottom:0px;\"><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" style=\"font-size:92%;\">PACKAGING<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n<p>Le couvre cascque Oiseau vient dans un blister personnalis\u00e9 de Flament rose, avec images du casque avec la housse de Oiseau et les instructions d&rsquo;usage.<\/p>\n<p>Le design et finition du blister changent chaque COOLCASC en cadeau original et excellent.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1157435134\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container\" style=\"margin-bottom:0px;\"><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" style=\"font-size:96%;\">ENTRETIEN ET  LAVAGE<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n<p>Un produit fabriqu\u00e9 dans lycra \u00ae<br \/>\nLaver un maximum \u00e0 30 \u00ba Celsius (65-85 F)<br \/>\nPas traitement d&rsquo;eau de Javel<br \/>\nS\u00e9chage en machine interdit<br \/>\nRepassage interdit.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1768002077\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container\" style=\"margin-bottom:0px;\"><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" style=\"font-size:96%;\">QUALITY<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n<p>Nos produits ont un design tr\u00e9s soign\u00e9 \u00a0et sont fabriqu\u00e9s par des mati\u00e8res premi\u00e8res de la plus haute qualit\u00e9.<\/p>\n<p>Tous les produits COOLCASC \u00ae r\u00e9visent manuellement et individuellement en suivant un protocole strict de contr\u00f4le de qualit\u00e9.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Lib\u00e9rez-vous comme cet oiseau bleu.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Mat\u00e9riel:<\/strong> 83% Polyamide y 17% Elast\u00e1n.<\/p>\n<p><strong>Taille unique: <\/strong> s&rsquo;adapte \u00e0 n&rsquo;importe quelle taille de casque.<\/p>\n<p><strong>Multisport:<\/strong> Apte aux casques de ski, de bicyclette, trottinette, patinage, skate et m\u00eame moto.<\/p>\n<p><strong>Adaptable<\/strong> aux casques d&rsquo;oreillette molle. Une ouverture post\u00e9rieure pour fixer les lunettes dans des casques de ski.<\/p>\n","protected":false},"featured_media":10563,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[112],"product_tag":[135,225,192],"class_list":{"0":"post-10403","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-animaux","7":"product_tag-casque","8":"product_tag-etui","9":"product_tag-rose-fr","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Couvre casque Oiseau - Coolcasc<\/title>\n<meta name=\"description\" content=\"Notre \u00e9tui de casque de Oiseau vient dans une taille pour toutes les tailles de casque.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coolcasc.com\/Housses%20de%20casque\/pajaro\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Couvre casque Oiseau - Coolcasc\" \/>\n<meta property=\"og:description\" content=\"Notre \u00e9tui de casque de Oiseau vient dans une taille pour toutes les tailles de casque.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coolcasc.com\/Housses de casque\/pajaro\/\" \/>\n<meta property=\"og:site_name\" content=\"Coolcasc\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/COOLCASC\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-29T10:16:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Colecciones\/Animales\/P\u00e1jaro-C.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"505\" \/>\n\t<meta property=\"og:image:height\" content=\"505\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@coolcasc\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/Housses de casque\\\/pajaro\\\/\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/Housses de casque\\\/pajaro\\\/\",\"name\":\"Couvre casque Oiseau - Coolcasc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/Housses de casque\\\/pajaro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/Housses de casque\\\/pajaro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/Colecciones\\\/Animales\\\/P\u00e1jaro-C.jpg\",\"datePublished\":\"2019-09-28T23:14:11+00:00\",\"dateModified\":\"2024-11-29T10:16:41+00:00\",\"description\":\"Notre \u00e9tui de casque de Oiseau vient dans une taille pour toutes les tailles de casque.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/Housses de casque\\\/pajaro\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/coolcasc.com\\\/Housses de casque\\\/pajaro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/Housses de casque\\\/pajaro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/Colecciones\\\/Animales\\\/P\u00e1jaro-C.jpg\",\"contentUrl\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/Colecciones\\\/Animales\\\/P\u00e1jaro-C.jpg\",\"width\":505,\"height\":505,\"caption\":\"Funda casco P\u00e1jaro\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/Housses de casque\\\/pajaro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Oiseau\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#website\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/\",\"name\":\"Coolcasc\",\"description\":\"Seguridad, moda y dise\u00f1o utilizando las fundas para casco Coolcasc en la pr\u00e1ctica de cualquier deporte.\",\"publisher\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/coolcasc.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#organization\",\"name\":\"Fundas para cascos Coolcasc\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Blue_header.png\",\"contentUrl\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Blue_header.png\",\"width\":300,\"height\":180,\"caption\":\"Fundas para cascos Coolcasc\"},\"image\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/COOLCASC\\\/\",\"https:\\\/\\\/x.com\\\/coolcasc\",\"https:\\\/\\\/www.instagram.com\\\/coolcasc\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Couvre casque Oiseau - Coolcasc","description":"Notre \u00e9tui de casque de Oiseau vient dans une taille pour toutes les tailles de casque.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coolcasc.com\/Housses de casque\/pajaro\/","og_locale":"fr_FR","og_type":"article","og_title":"Couvre casque Oiseau - Coolcasc","og_description":"Notre \u00e9tui de casque de Oiseau vient dans une taille pour toutes les tailles de casque.","og_url":"https:\/\/coolcasc.com\/Housses de casque\/pajaro\/","og_site_name":"Coolcasc","article_publisher":"https:\/\/www.facebook.com\/COOLCASC\/","article_modified_time":"2024-11-29T10:16:41+00:00","og_image":[{"width":505,"height":505,"url":"https:\/\/coolcasc.com\/wp-content\/uploads\/Colecciones\/Animales\/P\u00e1jaro-C.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@coolcasc","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coolcasc.com\/Housses de casque\/pajaro\/","url":"https:\/\/coolcasc.com\/Housses de casque\/pajaro\/","name":"Couvre casque Oiseau - Coolcasc","isPartOf":{"@id":"https:\/\/coolcasc.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/coolcasc.com\/Housses de casque\/pajaro\/#primaryimage"},"image":{"@id":"https:\/\/coolcasc.com\/Housses de casque\/pajaro\/#primaryimage"},"thumbnailUrl":"https:\/\/coolcasc.com\/wp-content\/uploads\/Colecciones\/Animales\/P\u00e1jaro-C.jpg","datePublished":"2019-09-28T23:14:11+00:00","dateModified":"2024-11-29T10:16:41+00:00","description":"Notre \u00e9tui de casque de Oiseau vient dans une taille pour toutes les tailles de casque.","breadcrumb":{"@id":"https:\/\/coolcasc.com\/Housses de casque\/pajaro\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coolcasc.com\/Housses de casque\/pajaro\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/coolcasc.com\/Housses de casque\/pajaro\/#primaryimage","url":"https:\/\/coolcasc.com\/wp-content\/uploads\/Colecciones\/Animales\/P\u00e1jaro-C.jpg","contentUrl":"https:\/\/coolcasc.com\/wp-content\/uploads\/Colecciones\/Animales\/P\u00e1jaro-C.jpg","width":505,"height":505,"caption":"Funda casco P\u00e1jaro"},{"@type":"BreadcrumbList","@id":"https:\/\/coolcasc.com\/Housses de casque\/pajaro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/coolcasc.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/coolcasc.com\/fr\/tienda\/"},{"@type":"ListItem","position":3,"name":"Oiseau"}]},{"@type":"WebSite","@id":"https:\/\/coolcasc.com\/#website","url":"https:\/\/coolcasc.com\/","name":"Coolcasc","description":"Seguridad, moda y dise\u00f1o utilizando las fundas para casco Coolcasc en la pr\u00e1ctica de cualquier deporte.","publisher":{"@id":"https:\/\/coolcasc.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coolcasc.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/coolcasc.com\/#organization","name":"Fundas para cascos Coolcasc","url":"https:\/\/coolcasc.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/coolcasc.com\/#\/schema\/logo\/image\/","url":"https:\/\/coolcasc.com\/wp-content\/uploads\/2018\/12\/Blue_header.png","contentUrl":"https:\/\/coolcasc.com\/wp-content\/uploads\/2018\/12\/Blue_header.png","width":300,"height":180,"caption":"Fundas para cascos Coolcasc"},"image":{"@id":"https:\/\/coolcasc.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/COOLCASC\/","https:\/\/x.com\/coolcasc","https:\/\/www.instagram.com\/coolcasc\/"]}]}},"_links":{"self":[{"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product\/10403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/comments?post=10403"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/media\/10563"}],"wp:attachment":[{"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/media?parent=10403"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product_brand?post=10403"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product_cat?post=10403"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product_tag?post=10403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}