{"id":11933,"date":"2020-09-30T10:03:22","date_gmt":"2020-09-30T10:03:22","guid":{"rendered":"https:\/\/coolcasc.com\/?post_type=product&#038;p=11933"},"modified":"2025-01-13T21:37:49","modified_gmt":"2025-01-13T21:37:49","slug":"rose-pon-pon-gris","status":"publish","type":"product","link":"https:\/\/coolcasc.com\/fr\/Housses de casque\/rose-pon-pon-gris\/","title":{"rendered":"Rose \/ Pon-Pon Gris"},"content":{"rendered":"<div class=\"row row-collapse row-full-width\"  id=\"row-1716895935\">\n\n\t<div id=\"col-1028609161\" class=\"col medium-6 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center dark\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_517342454\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:0px 10px 0 10px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Colecciones\/Exclusive\/Live\/Funda-casco-rosa-pon-pon-gris.jpg\" class=\"attachment-original size-original\" alt=\"Funda casco rosa pon-pon gris\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_517342454 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover hidden x md-x lg-x y md-y lg-y\" id=\"image_124848324\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:0px 10px 0 10px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"505\" height=\"505\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Colecciones\/Exclusive\/Live\/Azul-Pon-Pon-beige-3.jpg\" class=\"attachment-original size-original\" alt=\"Funda casco Azul Pon-Pon beige 3\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_124848324 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1379817030\" class=\"col medium-6 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1877036994\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:0px 10px 0 10px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"505\" height=\"505\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Colecciones\/CoolPrint\/Live\/Funda_casco_E009_2.jpg\" class=\"attachment-original size-original\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1877036994 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover hidden x md-x lg-x y md-y lg-y\" id=\"image_2053828860\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:0px 10px 0 10px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"505\" height=\"505\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Colecciones\/Exclusive\/Live\/Azul-Pon-Pon-beige-4.jpg\" class=\"attachment-original size-original\" alt=\"Funda casco Azul Pon-Pon beige\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2053828860 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"container section-title-container\" style=\"margin-bottom:0px;\"><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" style=\"font-size:92%;\">POURQUOI METTRE UN COOLCASC \u00c0 MON CASQUE?<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n<div class=\"row row-small\"  id=\"row-553086433\">\n\n\t<div id=\"col-1956597854\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<ul>\n<li style=\"text-align: left;\">Parce que je peux rapidement renouveler l&rsquo;aspect de mon casque.<\/li>\n<li style=\"text-align: left;\">Parce que je change de style quand je veux.<\/li>\n<li style=\"text-align: left;\">Parce qu&rsquo;il me pla\u00eet de diff\u00e9rer du reste.<\/li>\n<li style=\"text-align: left;\">Parce que je prot\u00e8ge mon casque des rayures.<\/li>\n<\/ul>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1956597854 > .col-inner {\n  margin: -35px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1604985100\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1359373670\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:-5px 0px 0px 0px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"505\" height=\"505\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Colecciones\/Exclusive\/Funda-casco-rosa-Pon-pon-gris-C.jpg\" class=\"attachment-original size-original\" alt=\"Funda casco rosa pon-pon gris C\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1359373670 {\n  width: 80%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1604985100 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 0px 0px -17px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1194821123\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<ul>\n<li style=\"text-align: left;\">Parce que je peux l\u00b4utiliser toute l&rsquo;ann\u00e9e, pour n&rsquo;importe quel casque et dans n&rsquo;importe quel sport.<\/li>\n<li style=\"text-align: left;\">Parce qu&rsquo;il me pla\u00eet de mettre une touche de couleur et d&rsquo;humour\u00a0 \u00e0 ma vie.<\/li>\n<li style=\"text-align: left;\">Parce qu&rsquo;\u00e0 je suis plus visible donc je vais beaucoup plus s\u00fbr.<\/li>\n<\/ul>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1194821123 > .col-inner {\n  margin: -35px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-553086433 > .col > .col-inner {\n  padding: 55px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n\n  <div class=\"banner has-hover\" id=\"banner-2008739657\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"1050\" height=\"700\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/2020\/10\/Funda-casco-rosa-pon-pon-gris-G.jpg\" class=\"bg attachment-original size-original\" alt=\"Funda casco rosa pon-pon gris\" \/>                                    \n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(255, 255, 255);border-width:15px 10px 0px 10px;\">\n\t<\/div>\n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-978178475\" class=\"text-box banner-layer x5 md-x5 lg-x5 y5 md-y5 lg-y5 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-left\">\n                  \n<h2 class=\"uppercase\"><strong>Rose \/ Pon-pon gris<\/strong><\/h2>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-978178475 {\n  width: 60%;\n}\n#text-box-978178475 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-978178475 {\n    width: 30%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-2008739657 {\n  padding-top: 61%;\n}\n#banner-2008739657 .banner-bg img {\n  object-position: 52% 15%;\n}\n<\/style>\n  <\/div>\n\n\n<div class=\"row\"  id=\"row-1907774021\">\n\n\t<div id=\"col-1061669529\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container\" style=\"margin-bottom:0px;\"><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" style=\"font-size:92%;\">PACKAGING<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n<p>Le produit vient dans un blister personnalis\u00e9 de Rose \/ Pon-pon gris, avec images du casque avec la housse de Rose \/ Pon-pon gris et les instructions d&rsquo;usage.<\/p>\n<p>Le design et finition du blister changent chaque COOLCASC en cadeau original et excellent.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1081099196\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container\" style=\"margin-bottom:0px;\"><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" style=\"font-size:96%;\">ENTRETIEN ET LAVAGE<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n<p>Un produit fabriqu\u00e9 dans lycra \u00ae<br \/>\nLaver un maximum \u00e0 30 \u00ba Celsius (65-85 F)<br \/>\nPas traitement d&rsquo;eau de Javel<br \/>\nS\u00e9chage en machine interdit<br \/>\nRepassage interdit.<\/p>\n<p>Ne pas laver avec des accessoires en fausse fourrure. Retirer avant de laver.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1818878639\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container\" style=\"margin-bottom:0px;\"><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" style=\"font-size:96%;\">QUALITY<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n<p>Nos produits ont un design tr\u00e9s soign\u00e9 \u00a0et sont fabriqu\u00e9s par des mati\u00e8res premi\u00e8res de la plus haute qualit\u00e9.<\/p>\n<p>Tous les produits COOLCASC \u00ae r\u00e9visent manuellement et individuellement en suivant un protocole strict de contr\u00f4le de qualit\u00e9.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p class=\"productDescription\">Si vous aimez le brillant et le rose, vous devez habiller votre casque avec cette couvre casque.<\/p>\n<p class=\"productDescription\">Il n&rsquo;y a aucune excuse!<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Mat\u00e9riel:<\/strong> 83% Polyamide y 17% Elast\u00e1n.<\/p>\n<p><strong>Taille unique: <\/strong> s&rsquo;adapte \u00e0 n&rsquo;importe quelle taille de casque.<\/p>\n<p><strong>Multisport:<\/strong> Apte aux casques de ski, de bicyclette, trottinette, patinage, skate et m\u00eame moto.<\/p>\n<p><strong>Adaptable<\/strong> aux casques d&rsquo;oreillette molle. Une ouverture post\u00e9rieure pour fixer les lunettes dans des casques de ski.<\/p>\n","protected":false},"featured_media":22891,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[97],"product_tag":[135,225,149,161,192],"class_list":{"0":"post-11933","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-exclusive-fr","7":"product_tag-casque","8":"product_tag-etui","9":"product_tag-exclusive-fr","10":"product_tag-gris-fr","11":"product_tag-rose-fr","13":"first","14":"instock","15":"featured","16":"taxable","17":"shipping-taxable","18":"purchasable","19":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Couvre casque Rose \/ Pon-pon gris - Coolcasc<\/title>\n<meta name=\"description\" content=\"Avec cet \u00e9tui pour casque Rose \/ Pon-pon gris, vous serez tr\u00e8s \u00e0 la mode. Bien que cela ne ressemble pas \u00e0 un chapeau, il s\u2019agit d\u2019un \u00e9tui \u00e0 casque avec pon-pon COOLCASC.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coolcasc.com\/fr\/Housses%20de%20casque\/rose-pon-pon-gris\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Couvre casque Rose \/ Pon-pon gris - Coolcasc\" \/>\n<meta property=\"og:description\" content=\"Avec cet \u00e9tui pour casque Rose \/ Pon-pon gris, vous serez tr\u00e8s \u00e0 la mode. Bien que cela ne ressemble pas \u00e0 un chapeau, il s\u2019agit d\u2019un \u00e9tui \u00e0 casque avec pon-pon COOLCASC.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coolcasc.com\/fr\/Housses de casque\/rose-pon-pon-gris\/\" \/>\n<meta property=\"og:site_name\" content=\"Coolcasc\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/COOLCASC\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-13T21:37:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coolcasc.com\/wp-content\/uploads\/2023\/10\/Funda-casco-rosa-Pon-pon-gris-D-500x500-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@coolcasc\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/Housses de casque\\\/rose-pon-pon-gris\\\/\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/Housses de casque\\\/rose-pon-pon-gris\\\/\",\"name\":\"Couvre casque Rose \\\/ Pon-pon gris - Coolcasc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/Housses de casque\\\/rose-pon-pon-gris\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/Housses de casque\\\/rose-pon-pon-gris\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Funda-casco-rosa-Pon-pon-gris-D-500x500-1.jpg\",\"datePublished\":\"2020-09-30T10:03:22+00:00\",\"dateModified\":\"2025-01-13T21:37:49+00:00\",\"description\":\"Avec cet \u00e9tui pour casque Rose \\\/ Pon-pon gris, vous serez tr\u00e8s \u00e0 la mode. Bien que cela ne ressemble pas \u00e0 un chapeau, il s\u2019agit d\u2019un \u00e9tui \u00e0 casque avec pon-pon COOLCASC.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/Housses de casque\\\/rose-pon-pon-gris\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/coolcasc.com\\\/fr\\\/Housses de casque\\\/rose-pon-pon-gris\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/Housses de casque\\\/rose-pon-pon-gris\\\/#primaryimage\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Funda-casco-rosa-Pon-pon-gris-D-500x500-1.jpg\",\"contentUrl\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Funda-casco-rosa-Pon-pon-gris-D-500x500-1.jpg\",\"width\":500,\"height\":500,\"caption\":\"Funda casco rosa Pon-pon gris\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/Housses de casque\\\/rose-pon-pon-gris\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rose \\\/ Pon-Pon Gris\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#website\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/\",\"name\":\"Coolcasc\",\"description\":\"Seguridad, moda y dise\u00f1o utilizando las fundas para casco Coolcasc en la pr\u00e1ctica de cualquier deporte.\",\"publisher\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/coolcasc.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#organization\",\"name\":\"Fundas para cascos Coolcasc\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Blue_header.png\",\"contentUrl\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Blue_header.png\",\"width\":300,\"height\":180,\"caption\":\"Fundas para cascos Coolcasc\"},\"image\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/COOLCASC\\\/\",\"https:\\\/\\\/x.com\\\/coolcasc\",\"https:\\\/\\\/www.instagram.com\\\/coolcasc\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Couvre casque Rose \/ Pon-pon gris - Coolcasc","description":"Avec cet \u00e9tui pour casque Rose \/ Pon-pon gris, vous serez tr\u00e8s \u00e0 la mode. Bien que cela ne ressemble pas \u00e0 un chapeau, il s\u2019agit d\u2019un \u00e9tui \u00e0 casque avec pon-pon COOLCASC.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coolcasc.com\/fr\/Housses de casque\/rose-pon-pon-gris\/","og_locale":"fr_FR","og_type":"article","og_title":"Couvre casque Rose \/ Pon-pon gris - Coolcasc","og_description":"Avec cet \u00e9tui pour casque Rose \/ Pon-pon gris, vous serez tr\u00e8s \u00e0 la mode. Bien que cela ne ressemble pas \u00e0 un chapeau, il s\u2019agit d\u2019un \u00e9tui \u00e0 casque avec pon-pon COOLCASC.","og_url":"https:\/\/coolcasc.com\/fr\/Housses de casque\/rose-pon-pon-gris\/","og_site_name":"Coolcasc","article_publisher":"https:\/\/www.facebook.com\/COOLCASC\/","article_modified_time":"2025-01-13T21:37:49+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/coolcasc.com\/wp-content\/uploads\/2023\/10\/Funda-casco-rosa-Pon-pon-gris-D-500x500-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@coolcasc","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coolcasc.com\/fr\/Housses de casque\/rose-pon-pon-gris\/","url":"https:\/\/coolcasc.com\/fr\/Housses de casque\/rose-pon-pon-gris\/","name":"Couvre casque Rose \/ Pon-pon gris - Coolcasc","isPartOf":{"@id":"https:\/\/coolcasc.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/coolcasc.com\/fr\/Housses de casque\/rose-pon-pon-gris\/#primaryimage"},"image":{"@id":"https:\/\/coolcasc.com\/fr\/Housses de casque\/rose-pon-pon-gris\/#primaryimage"},"thumbnailUrl":"https:\/\/coolcasc.com\/wp-content\/uploads\/2023\/10\/Funda-casco-rosa-Pon-pon-gris-D-500x500-1.jpg","datePublished":"2020-09-30T10:03:22+00:00","dateModified":"2025-01-13T21:37:49+00:00","description":"Avec cet \u00e9tui pour casque Rose \/ Pon-pon gris, vous serez tr\u00e8s \u00e0 la mode. Bien que cela ne ressemble pas \u00e0 un chapeau, il s\u2019agit d\u2019un \u00e9tui \u00e0 casque avec pon-pon COOLCASC.","breadcrumb":{"@id":"https:\/\/coolcasc.com\/fr\/Housses de casque\/rose-pon-pon-gris\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coolcasc.com\/fr\/Housses de casque\/rose-pon-pon-gris\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/coolcasc.com\/fr\/Housses de casque\/rose-pon-pon-gris\/#primaryimage","url":"https:\/\/coolcasc.com\/wp-content\/uploads\/2023\/10\/Funda-casco-rosa-Pon-pon-gris-D-500x500-1.jpg","contentUrl":"https:\/\/coolcasc.com\/wp-content\/uploads\/2023\/10\/Funda-casco-rosa-Pon-pon-gris-D-500x500-1.jpg","width":500,"height":500,"caption":"Funda casco rosa Pon-pon gris"},{"@type":"BreadcrumbList","@id":"https:\/\/coolcasc.com\/fr\/Housses de casque\/rose-pon-pon-gris\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/coolcasc.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/coolcasc.com\/fr\/tienda\/"},{"@type":"ListItem","position":3,"name":"Rose \/ Pon-Pon Gris"}]},{"@type":"WebSite","@id":"https:\/\/coolcasc.com\/#website","url":"https:\/\/coolcasc.com\/","name":"Coolcasc","description":"Seguridad, moda y dise\u00f1o utilizando las fundas para casco Coolcasc en la pr\u00e1ctica de cualquier deporte.","publisher":{"@id":"https:\/\/coolcasc.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coolcasc.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/coolcasc.com\/#organization","name":"Fundas para cascos Coolcasc","url":"https:\/\/coolcasc.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/coolcasc.com\/#\/schema\/logo\/image\/","url":"https:\/\/coolcasc.com\/wp-content\/uploads\/2018\/12\/Blue_header.png","contentUrl":"https:\/\/coolcasc.com\/wp-content\/uploads\/2018\/12\/Blue_header.png","width":300,"height":180,"caption":"Fundas para cascos Coolcasc"},"image":{"@id":"https:\/\/coolcasc.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/COOLCASC\/","https:\/\/x.com\/coolcasc","https:\/\/www.instagram.com\/coolcasc\/"]}]}},"_links":{"self":[{"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product\/11933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/comments?post=11933"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/media\/22891"}],"wp:attachment":[{"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/media?parent=11933"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product_brand?post=11933"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product_cat?post=11933"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product_tag?post=11933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}