{"id":12588,"date":"2020-01-23T16:54:34","date_gmt":"2020-01-23T16:54:34","guid":{"rendered":"https:\/\/coolcasc.com\/funda-para-casco\/housse-a-masque-de-ski-turquoise\/"},"modified":"2026-03-06T13:09:43","modified_gmt":"2026-03-06T13:09:43","slug":"housse-a-masque-de-ski-turquoise","status":"publish","type":"product","link":"https:\/\/coolcasc.com\/fr\/Housses de casque\/housse-a-masque-de-ski-turquoise\/","title":{"rendered":"Couvre masque Turquoise"},"content":{"rendered":"<div class=\"row\"  id=\"row-1889835275\">\n\n\t<div id=\"col-331362518\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_915897492\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"505\" height=\"505\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/gafas\/live\/618_SB1-2.jpg\" class=\"attachment-original size-original\" alt=\"Funda gafas\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_915897492 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p class=\"productDescription\">COOLMASC housse \u00e0 masque de ski Turquoise.<\/p>\n<p class=\"productDescription\">Il s&rsquo;adapte \u00e0 presque tous les masques.<\/p>\n<p><strong>Material:<\/strong>Fabriqu\u00e9 avec du plastique \u00e0 partir de bouteilles recycl\u00e9es 83% Polyamide RPET et 17% Spandex. Lavable a machine, cycle doux.<\/p>\n<p>Utilisez-le pour nettoyer et prot\u00e9ger votre masque.<\/p>\n<p>Facil a mettre et \u00e0 enlever.<\/p>\n<p><strong>Produit \u00e9cologique.<\/strong><\/p>\n","protected":false},"featured_media":11267,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[271,430],"product_tag":[225,280,289],"class_list":["post-12588","product","type-product","status-publish","has-post-thumbnail","product_cat-couvre-masques-coolmasc","product_cat-rpet-fr","product_tag-etui","product_tag-masque","product_tag-turquoise-fr","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Couvre masque Turquoise - Coolmasc<\/title>\n<meta name=\"description\" content=\"Etui \u00e0 lunettes &quot;Turquoise&quot;, avec 88% de polyester recycl\u00e9 provenant de 3 bouteilles en plastique. Pour ceux qui aiment essayer de nouvelles choses et \u00eatre prot\u00e9g\u00e9s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coolcasc.com\/fr\/Housses%20de%20casque\/housse-a-masque-de-ski-turquoise\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Couvre masque Turquoise - Coolmasc\" \/>\n<meta property=\"og:description\" content=\"Etui \u00e0 lunettes &quot;Turquoise&quot;, avec 88% de polyester recycl\u00e9 provenant de 3 bouteilles en plastique. Pour ceux qui aiment essayer de nouvelles choses et \u00eatre prot\u00e9g\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coolcasc.com\/fr\/Housses de casque\/housse-a-masque-de-ski-turquoise\/\" \/>\n<meta property=\"og:site_name\" content=\"Coolcasc\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/COOLCASC\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-06T13:09:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coolcasc.com\/wp-content\/uploads\/gafas\/Funda-gafas-turquesa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@coolcasc\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/Housses de casque\\\/housse-a-masque-de-ski-turquoise\\\/\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/Housses de casque\\\/housse-a-masque-de-ski-turquoise\\\/\",\"name\":\"Couvre masque Turquoise - Coolmasc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/Housses de casque\\\/housse-a-masque-de-ski-turquoise\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/Housses de casque\\\/housse-a-masque-de-ski-turquoise\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/gafas\\\/Funda-gafas-turquesa.jpg\",\"datePublished\":\"2020-01-23T16:54:34+00:00\",\"dateModified\":\"2026-03-06T13:09:43+00:00\",\"description\":\"Etui \u00e0 lunettes \\\"Turquoise\\\", avec 88% de polyester recycl\u00e9 provenant de 3 bouteilles en plastique. Pour ceux qui aiment essayer de nouvelles choses et \u00eatre prot\u00e9g\u00e9s.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/Housses de casque\\\/housse-a-masque-de-ski-turquoise\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/coolcasc.com\\\/fr\\\/Housses de casque\\\/housse-a-masque-de-ski-turquoise\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/Housses de casque\\\/housse-a-masque-de-ski-turquoise\\\/#primaryimage\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/gafas\\\/Funda-gafas-turquesa.jpg\",\"contentUrl\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/gafas\\\/Funda-gafas-turquesa.jpg\",\"width\":500,\"height\":432,\"caption\":\"Housse \u00e0 masque de ski Turquoise\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/Housses de casque\\\/housse-a-masque-de-ski-turquoise\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Couvre masque Turquoise\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#website\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/\",\"name\":\"Coolcasc\",\"description\":\"Seguridad, moda y dise\u00f1o utilizando las fundas para casco Coolcasc en la pr\u00e1ctica de cualquier deporte.\",\"publisher\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/coolcasc.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#organization\",\"name\":\"Fundas para cascos Coolcasc\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Blue_header.png\",\"contentUrl\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Blue_header.png\",\"width\":300,\"height\":180,\"caption\":\"Fundas para cascos Coolcasc\"},\"image\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/COOLCASC\\\/\",\"https:\\\/\\\/x.com\\\/coolcasc\",\"https:\\\/\\\/www.instagram.com\\\/coolcasc\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Couvre masque Turquoise - Coolmasc","description":"Etui \u00e0 lunettes \"Turquoise\", avec 88% de polyester recycl\u00e9 provenant de 3 bouteilles en plastique. Pour ceux qui aiment essayer de nouvelles choses et \u00eatre prot\u00e9g\u00e9s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coolcasc.com\/fr\/Housses de casque\/housse-a-masque-de-ski-turquoise\/","og_locale":"fr_FR","og_type":"article","og_title":"Couvre masque Turquoise - Coolmasc","og_description":"Etui \u00e0 lunettes \"Turquoise\", avec 88% de polyester recycl\u00e9 provenant de 3 bouteilles en plastique. Pour ceux qui aiment essayer de nouvelles choses et \u00eatre prot\u00e9g\u00e9s.","og_url":"https:\/\/coolcasc.com\/fr\/Housses de casque\/housse-a-masque-de-ski-turquoise\/","og_site_name":"Coolcasc","article_publisher":"https:\/\/www.facebook.com\/COOLCASC\/","article_modified_time":"2026-03-06T13:09:43+00:00","og_image":[{"width":500,"height":432,"url":"https:\/\/coolcasc.com\/wp-content\/uploads\/gafas\/Funda-gafas-turquesa.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@coolcasc","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coolcasc.com\/fr\/Housses de casque\/housse-a-masque-de-ski-turquoise\/","url":"https:\/\/coolcasc.com\/fr\/Housses de casque\/housse-a-masque-de-ski-turquoise\/","name":"Couvre masque Turquoise - Coolmasc","isPartOf":{"@id":"https:\/\/coolcasc.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/coolcasc.com\/fr\/Housses de casque\/housse-a-masque-de-ski-turquoise\/#primaryimage"},"image":{"@id":"https:\/\/coolcasc.com\/fr\/Housses de casque\/housse-a-masque-de-ski-turquoise\/#primaryimage"},"thumbnailUrl":"https:\/\/coolcasc.com\/wp-content\/uploads\/gafas\/Funda-gafas-turquesa.jpg","datePublished":"2020-01-23T16:54:34+00:00","dateModified":"2026-03-06T13:09:43+00:00","description":"Etui \u00e0 lunettes \"Turquoise\", avec 88% de polyester recycl\u00e9 provenant de 3 bouteilles en plastique. Pour ceux qui aiment essayer de nouvelles choses et \u00eatre prot\u00e9g\u00e9s.","breadcrumb":{"@id":"https:\/\/coolcasc.com\/fr\/Housses de casque\/housse-a-masque-de-ski-turquoise\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coolcasc.com\/fr\/Housses de casque\/housse-a-masque-de-ski-turquoise\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/coolcasc.com\/fr\/Housses de casque\/housse-a-masque-de-ski-turquoise\/#primaryimage","url":"https:\/\/coolcasc.com\/wp-content\/uploads\/gafas\/Funda-gafas-turquesa.jpg","contentUrl":"https:\/\/coolcasc.com\/wp-content\/uploads\/gafas\/Funda-gafas-turquesa.jpg","width":500,"height":432,"caption":"Housse \u00e0 masque de ski Turquoise"},{"@type":"BreadcrumbList","@id":"https:\/\/coolcasc.com\/fr\/Housses de casque\/housse-a-masque-de-ski-turquoise\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/coolcasc.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/coolcasc.com\/fr\/tienda\/"},{"@type":"ListItem","position":3,"name":"Couvre masque Turquoise"}]},{"@type":"WebSite","@id":"https:\/\/coolcasc.com\/#website","url":"https:\/\/coolcasc.com\/","name":"Coolcasc","description":"Seguridad, moda y dise\u00f1o utilizando las fundas para casco Coolcasc en la pr\u00e1ctica de cualquier deporte.","publisher":{"@id":"https:\/\/coolcasc.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coolcasc.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/coolcasc.com\/#organization","name":"Fundas para cascos Coolcasc","url":"https:\/\/coolcasc.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/coolcasc.com\/#\/schema\/logo\/image\/","url":"https:\/\/coolcasc.com\/wp-content\/uploads\/2018\/12\/Blue_header.png","contentUrl":"https:\/\/coolcasc.com\/wp-content\/uploads\/2018\/12\/Blue_header.png","width":300,"height":180,"caption":"Fundas para cascos Coolcasc"},"image":{"@id":"https:\/\/coolcasc.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/COOLCASC\/","https:\/\/x.com\/coolcasc","https:\/\/www.instagram.com\/coolcasc\/"]}]}},"_links":{"self":[{"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product\/12588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/comments?post=12588"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/media\/11267"}],"wp:attachment":[{"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/media?parent=12588"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product_brand?post=12588"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product_cat?post=12588"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product_tag?post=12588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}