{"id":22411,"date":"2023-09-20T00:00:00","date_gmt":"2023-09-20T00:00:00","guid":{"rendered":"https:\/\/coolcasc.com\/?post_type=product&#038;p=22411"},"modified":"2023-10-19T21:47:46","modified_gmt":"2023-10-19T21:47:46","slug":"pierre","status":"publish","type":"product","link":"https:\/\/coolcasc.com\/fr\/Housses de casque\/pierre\/","title":{"rendered":"Pierre"},"content":{"rendered":"<div class=\"row\"  id=\"row-1758903830\">\n\n\t<div id=\"col-1258721026\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner dark\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_341833146\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:0px 10px 0px 10px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/2023\/10\/175_SAP.jpg\" class=\"attachment-original size-original\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_341833146 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-803491303\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1299941282\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:0px 10px 0px 10px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/2023\/10\/175_SB2MOUNTAIN.jpg\" class=\"attachment-original size-original\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1299941282 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-1758903830 > .col > .col-inner {\n  padding: 33px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n<div class=\"container section-title-container\" style=\"margin-bottom:0px;\"><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" style=\"font-size:92%;\">POURQUOI METTRE UN COOLCASC \u00c0 MON CASQUE?<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n<div class=\"row row-small\"  id=\"row-462411354\">\n\n\t<div id=\"col-1369822518\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<ul>\n<li style=\"text-align: left;\">Parce que je peux rapidement renouveler l&rsquo;aspect de mon casque..<\/li>\n<li style=\"text-align: left;\">Parce que je change de style quand je veux.<\/li>\n<li style=\"text-align: left;\">Parce qu&rsquo;il me pla\u00eet de diff\u00e9rer du reste.<\/li>\n<li style=\"text-align: left;\">Parce que je prot\u00e8ge mon casque des rayures.<\/li>\n<\/ul>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1369822518 > .col-inner {\n  margin: -35px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1856017545\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_233471414\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:-5px 0px 0px 0px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"505\" height=\"505\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/2023\/09\/175_HRAC.jpg\" class=\"attachment-original size-original\" alt=\"Piedra derecha 3\/4\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_233471414 {\n  width: 80%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1856017545 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 0px 0px -17px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1663288854\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<ul>\n<li style=\"text-align: left;\">Parce que je peux l\u00b4utiliser toute l&rsquo;ann\u00e9e, pour n&rsquo;importe quel casque et dans n&rsquo;importe quel sport.<\/li>\n<li style=\"text-align: left;\">Parce qu&rsquo;il me pla\u00eet de mettre une touche de couleur et d&rsquo;humour\u00a0 \u00e0 ma vie.<\/li>\n<li style=\"text-align: left;\">Parce qu&rsquo;\u00e0 je suis plus visible donc je vais beaucoup plus s\u00fbr.<\/li>\n<\/ul>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1663288854 > .col-inner {\n  margin: -35px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-462411354 > .col > .col-inner {\n  padding: 55px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n<div class=\"row\"  id=\"row-167951908\">\n\n\t<div id=\"col-281538404\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container\" style=\"margin-bottom:0px;\"><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" style=\"font-size:92%;\">PACKAGING<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n<p>Le produit vient dans un blister personnalis\u00e9 de Pierre, avec images du casque avec la housse de Pierre et les instructions d&rsquo;usage.<\/p>\n<p>Le design et finition du blister changent chaque COOLCASC en cadeau original et excellent.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-999914433\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container\" style=\"margin-bottom:0px;\"><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" style=\"font-size:96%;\">ENTRETIEN ET LAVAGE<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n<p>Un produit fabriqu\u00e9 dans lycra \u00ae<br \/>\nLaver un maximum \u00e0 30 \u00ba Celsius (65-85 F)<br \/>\nPas traitement d&rsquo;eau de Javel<br \/>\nS\u00e9chage en machine interdit<br \/>\nRepassage interdit.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1386311932\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container\" style=\"margin-bottom:0px;\"><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" style=\"font-size:96%;\">QUALITY<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n<p>Nos produits ont un design tr\u00e9s soign\u00e9 \u00a0et sont fabriqu\u00e9s par des mati\u00e8res premi\u00e8res de la plus haute qualit\u00e9.<\/p>\n<p>Tous les produits COOLCASC \u00ae r\u00e9visent manuellement et individuellement en suivant un protocole strict de contr\u00f4le de qualit\u00e9.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p class=\"productDescription\">Ajoutez une texture de pierre d&rsquo;ardoise \u00e0 votre casque, pour une finition antichoc.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Mat\u00e9riel:<\/strong> 83% Polyamide y 17% Elast\u00e1n.<\/p>\n<p><strong>Taille unique: <\/strong> s&rsquo;adapte \u00e0 n&rsquo;importe quelle taille de casque.<\/p>\n<p><strong>Multisport:<\/strong> Apte aux casques de ski, de bicyclette, trottinette, patinage, skate et m\u00eame moto.<\/p>\n<p><strong>Adaptable<\/strong> aux casques d&rsquo;oreillette molle. Une ouverture post\u00e9rieure pour fixer les lunettes dans des casques de ski.<\/p>\n","protected":false},"featured_media":24663,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[89],"product_tag":[135,119,225,176,192],"class_list":["post-22411","product","type-product","status-publish","has-post-thumbnail","product_cat-cool-print-fr","product_tag-casque","product_tag-cool-print-fr","product_tag-etui","product_tag-noir","product_tag-rose-fr","first","instock","featured","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Couvre casque Pierre - Coolcasc<\/title>\n<meta name=\"description\" content=\"Couvre casque Pierre by Coolcasc\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coolcasc.com\/fr\/Housses%20de%20casque\/pierre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Couvre casque Pierre - Coolcasc\" \/>\n<meta property=\"og:description\" content=\"Couvre casque Pierre by Coolcasc\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coolcasc.com\/fr\/Housses de casque\/pierre\/\" \/>\n<meta property=\"og:site_name\" content=\"Coolcasc\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/COOLCASC\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-19T21:47:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coolcasc.com\/wp-content\/uploads\/2023\/09\/175_HRAD.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"505\" \/>\n\t<meta property=\"og:image:height\" content=\"505\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@coolcasc\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/Housses de casque\\\/pierre\\\/\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/Housses de casque\\\/pierre\\\/\",\"name\":\"Couvre casque Pierre - Coolcasc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/Housses de casque\\\/pierre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/Housses de casque\\\/pierre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/175.jpg\",\"datePublished\":\"2023-09-20T00:00:00+00:00\",\"dateModified\":\"2023-10-19T21:47:46+00:00\",\"description\":\"Couvre casque Pierre by Coolcasc\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/Housses de casque\\\/pierre\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/coolcasc.com\\\/fr\\\/Housses de casque\\\/pierre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/Housses de casque\\\/pierre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/175.jpg\",\"contentUrl\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/175.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/Housses de casque\\\/pierre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pierre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#website\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/\",\"name\":\"Coolcasc\",\"description\":\"Seguridad, moda y dise\u00f1o utilizando las fundas para casco Coolcasc en la pr\u00e1ctica de cualquier deporte.\",\"publisher\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/coolcasc.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#organization\",\"name\":\"Fundas para cascos Coolcasc\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Blue_header.png\",\"contentUrl\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Blue_header.png\",\"width\":300,\"height\":180,\"caption\":\"Fundas para cascos Coolcasc\"},\"image\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/COOLCASC\\\/\",\"https:\\\/\\\/x.com\\\/coolcasc\",\"https:\\\/\\\/www.instagram.com\\\/coolcasc\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Couvre casque Pierre - Coolcasc","description":"Couvre casque Pierre by Coolcasc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coolcasc.com\/fr\/Housses de casque\/pierre\/","og_locale":"fr_FR","og_type":"article","og_title":"Couvre casque Pierre - Coolcasc","og_description":"Couvre casque Pierre by Coolcasc","og_url":"https:\/\/coolcasc.com\/fr\/Housses de casque\/pierre\/","og_site_name":"Coolcasc","article_publisher":"https:\/\/www.facebook.com\/COOLCASC\/","article_modified_time":"2023-10-19T21:47:46+00:00","og_image":[{"width":505,"height":505,"url":"https:\/\/coolcasc.com\/wp-content\/uploads\/2023\/09\/175_HRAD.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@coolcasc","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coolcasc.com\/fr\/Housses de casque\/pierre\/","url":"https:\/\/coolcasc.com\/fr\/Housses de casque\/pierre\/","name":"Couvre casque Pierre - Coolcasc","isPartOf":{"@id":"https:\/\/coolcasc.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/coolcasc.com\/fr\/Housses de casque\/pierre\/#primaryimage"},"image":{"@id":"https:\/\/coolcasc.com\/fr\/Housses de casque\/pierre\/#primaryimage"},"thumbnailUrl":"https:\/\/coolcasc.com\/wp-content\/uploads\/2023\/09\/175.jpg","datePublished":"2023-09-20T00:00:00+00:00","dateModified":"2023-10-19T21:47:46+00:00","description":"Couvre casque Pierre by Coolcasc","breadcrumb":{"@id":"https:\/\/coolcasc.com\/fr\/Housses de casque\/pierre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coolcasc.com\/fr\/Housses de casque\/pierre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/coolcasc.com\/fr\/Housses de casque\/pierre\/#primaryimage","url":"https:\/\/coolcasc.com\/wp-content\/uploads\/2023\/09\/175.jpg","contentUrl":"https:\/\/coolcasc.com\/wp-content\/uploads\/2023\/09\/175.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/coolcasc.com\/fr\/Housses de casque\/pierre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/coolcasc.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/coolcasc.com\/fr\/tienda\/"},{"@type":"ListItem","position":3,"name":"Pierre"}]},{"@type":"WebSite","@id":"https:\/\/coolcasc.com\/#website","url":"https:\/\/coolcasc.com\/","name":"Coolcasc","description":"Seguridad, moda y dise\u00f1o utilizando las fundas para casco Coolcasc en la pr\u00e1ctica de cualquier deporte.","publisher":{"@id":"https:\/\/coolcasc.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coolcasc.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/coolcasc.com\/#organization","name":"Fundas para cascos Coolcasc","url":"https:\/\/coolcasc.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/coolcasc.com\/#\/schema\/logo\/image\/","url":"https:\/\/coolcasc.com\/wp-content\/uploads\/2018\/12\/Blue_header.png","contentUrl":"https:\/\/coolcasc.com\/wp-content\/uploads\/2018\/12\/Blue_header.png","width":300,"height":180,"caption":"Fundas para cascos Coolcasc"},"image":{"@id":"https:\/\/coolcasc.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/COOLCASC\/","https:\/\/x.com\/coolcasc","https:\/\/www.instagram.com\/coolcasc\/"]}]}},"_links":{"self":[{"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product\/22411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/comments?post=22411"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/media\/24663"}],"wp:attachment":[{"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/media?parent=22411"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product_brand?post=22411"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product_cat?post=22411"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product_tag?post=22411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}