{"id":22535,"date":"2023-09-20T00:00:24","date_gmt":"2023-09-20T00:00:24","guid":{"rendered":"https:\/\/coolcasc.com\/?post_type=product&#038;p=22535"},"modified":"2026-03-06T13:07:59","modified_gmt":"2026-03-06T13:07:59","slug":"housse-a-masque-de-ski-electro","status":"publish","type":"product","link":"https:\/\/coolcasc.com\/fr\/Housses de casque\/housse-a-masque-de-ski-electro\/","title":{"rendered":"Couvre masque Electro"},"content":{"rendered":"<div class=\"row\"  id=\"row-1783421757\">\n\n\t<div id=\"col-514917178\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1361508796\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/2023\/10\/636_SB1.jpg\" class=\"attachment-original size-original\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1361508796 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p class=\"productDescription\">COOLMASC housse \u00e0 masque de ski Electro.<\/p>\n<p class=\"productDescription\">Il s&rsquo;adapte \u00e0 presque tous les masques.<\/p>\n<p><strong>Material:<\/strong>Fabriqu\u00e9 avec du plastique \u00e0 partir de bouteilles recycl\u00e9es 83% Polyamide RPET et 17% Spandex. Lavable a machine, cycle doux.<\/p>\n<p>Utilisez-le pour nettoyer et prot\u00e9ger votre masque.<\/p>\n<p>Facil a mettre et \u00e0 enlever.<\/p>\n<p><strong>Produit \u00e9cologique.<\/strong><\/p>\n","protected":false},"featured_media":22495,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[271,430],"product_tag":[217,225,290,280],"class_list":["post-22535","product","type-product","status-publish","has-post-thumbnail","product_cat-couvre-masques-coolmasc","product_cat-rpet-fr","product_tag-blanc","product_tag-etui","product_tag-leopard","product_tag-masque","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Couvre masque Electro - Coolmasc<\/title>\n<meta name=\"description\" content=\"Etui \u00e0 lunettes &quot;Electro&quot;, avec 88% de polyester recycl\u00e9 provenant de 3 bouteilles en plastique. Pour ceux qui aiment essayer de nouvelles choses et \u00eatre prot\u00e9g\u00e9s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coolcasc.com\/fr\/Housses%20de%20casque\/housse-a-masque-de-ski-electro\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Couvre masque Electro - Coolmasc\" \/>\n<meta property=\"og:description\" content=\"Etui \u00e0 lunettes &quot;Electro&quot;, avec 88% de polyester recycl\u00e9 provenant de 3 bouteilles en plastique. Pour ceux qui aiment essayer de nouvelles choses et \u00eatre prot\u00e9g\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coolcasc.com\/fr\/Housses de casque\/housse-a-masque-de-ski-electro\/\" \/>\n<meta property=\"og:site_name\" content=\"Coolcasc\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/COOLCASC\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-06T13:07:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coolcasc.com\/wp-content\/uploads\/2023\/09\/636_HR.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@coolcasc\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/Housses de casque\\\/housse-a-masque-de-ski-electro\\\/\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/Housses de casque\\\/housse-a-masque-de-ski-electro\\\/\",\"name\":\"Couvre masque Electro - Coolmasc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/Housses de casque\\\/housse-a-masque-de-ski-electro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/Housses de casque\\\/housse-a-masque-de-ski-electro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/636_HR.jpg\",\"datePublished\":\"2023-09-20T00:00:24+00:00\",\"dateModified\":\"2026-03-06T13:07:59+00:00\",\"description\":\"Etui \u00e0 lunettes \\\"Electro\\\", avec 88% de polyester recycl\u00e9 provenant de 3 bouteilles en plastique. Pour ceux qui aiment essayer de nouvelles choses et \u00eatre prot\u00e9g\u00e9s.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/Housses de casque\\\/housse-a-masque-de-ski-electro\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/coolcasc.com\\\/fr\\\/Housses de casque\\\/housse-a-masque-de-ski-electro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/Housses de casque\\\/housse-a-masque-de-ski-electro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/636_HR.jpg\",\"contentUrl\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/636_HR.jpg\",\"width\":500,\"height\":432,\"caption\":\"coolmasc Electro\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/Housses de casque\\\/housse-a-masque-de-ski-electro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Couvre masque Electro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#website\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/\",\"name\":\"Coolcasc\",\"description\":\"Seguridad, moda y dise\u00f1o utilizando las fundas para casco Coolcasc en la pr\u00e1ctica de cualquier deporte.\",\"publisher\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/coolcasc.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#organization\",\"name\":\"Fundas para cascos Coolcasc\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Blue_header.png\",\"contentUrl\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Blue_header.png\",\"width\":300,\"height\":180,\"caption\":\"Fundas para cascos Coolcasc\"},\"image\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/COOLCASC\\\/\",\"https:\\\/\\\/x.com\\\/coolcasc\",\"https:\\\/\\\/www.instagram.com\\\/coolcasc\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Couvre masque Electro - Coolmasc","description":"Etui \u00e0 lunettes \"Electro\", avec 88% de polyester recycl\u00e9 provenant de 3 bouteilles en plastique. Pour ceux qui aiment essayer de nouvelles choses et \u00eatre prot\u00e9g\u00e9s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coolcasc.com\/fr\/Housses de casque\/housse-a-masque-de-ski-electro\/","og_locale":"fr_FR","og_type":"article","og_title":"Couvre masque Electro - Coolmasc","og_description":"Etui \u00e0 lunettes \"Electro\", avec 88% de polyester recycl\u00e9 provenant de 3 bouteilles en plastique. Pour ceux qui aiment essayer de nouvelles choses et \u00eatre prot\u00e9g\u00e9s.","og_url":"https:\/\/coolcasc.com\/fr\/Housses de casque\/housse-a-masque-de-ski-electro\/","og_site_name":"Coolcasc","article_publisher":"https:\/\/www.facebook.com\/COOLCASC\/","article_modified_time":"2026-03-06T13:07:59+00:00","og_image":[{"width":500,"height":432,"url":"https:\/\/coolcasc.com\/wp-content\/uploads\/2023\/09\/636_HR.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@coolcasc","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coolcasc.com\/fr\/Housses de casque\/housse-a-masque-de-ski-electro\/","url":"https:\/\/coolcasc.com\/fr\/Housses de casque\/housse-a-masque-de-ski-electro\/","name":"Couvre masque Electro - Coolmasc","isPartOf":{"@id":"https:\/\/coolcasc.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/coolcasc.com\/fr\/Housses de casque\/housse-a-masque-de-ski-electro\/#primaryimage"},"image":{"@id":"https:\/\/coolcasc.com\/fr\/Housses de casque\/housse-a-masque-de-ski-electro\/#primaryimage"},"thumbnailUrl":"https:\/\/coolcasc.com\/wp-content\/uploads\/2023\/09\/636_HR.jpg","datePublished":"2023-09-20T00:00:24+00:00","dateModified":"2026-03-06T13:07:59+00:00","description":"Etui \u00e0 lunettes \"Electro\", avec 88% de polyester recycl\u00e9 provenant de 3 bouteilles en plastique. Pour ceux qui aiment essayer de nouvelles choses et \u00eatre prot\u00e9g\u00e9s.","breadcrumb":{"@id":"https:\/\/coolcasc.com\/fr\/Housses de casque\/housse-a-masque-de-ski-electro\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coolcasc.com\/fr\/Housses de casque\/housse-a-masque-de-ski-electro\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/coolcasc.com\/fr\/Housses de casque\/housse-a-masque-de-ski-electro\/#primaryimage","url":"https:\/\/coolcasc.com\/wp-content\/uploads\/2023\/09\/636_HR.jpg","contentUrl":"https:\/\/coolcasc.com\/wp-content\/uploads\/2023\/09\/636_HR.jpg","width":500,"height":432,"caption":"coolmasc Electro"},{"@type":"BreadcrumbList","@id":"https:\/\/coolcasc.com\/fr\/Housses de casque\/housse-a-masque-de-ski-electro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/coolcasc.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/coolcasc.com\/fr\/tienda\/"},{"@type":"ListItem","position":3,"name":"Couvre masque Electro"}]},{"@type":"WebSite","@id":"https:\/\/coolcasc.com\/#website","url":"https:\/\/coolcasc.com\/","name":"Coolcasc","description":"Seguridad, moda y dise\u00f1o utilizando las fundas para casco Coolcasc en la pr\u00e1ctica de cualquier deporte.","publisher":{"@id":"https:\/\/coolcasc.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coolcasc.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/coolcasc.com\/#organization","name":"Fundas para cascos Coolcasc","url":"https:\/\/coolcasc.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/coolcasc.com\/#\/schema\/logo\/image\/","url":"https:\/\/coolcasc.com\/wp-content\/uploads\/2018\/12\/Blue_header.png","contentUrl":"https:\/\/coolcasc.com\/wp-content\/uploads\/2018\/12\/Blue_header.png","width":300,"height":180,"caption":"Fundas para cascos Coolcasc"},"image":{"@id":"https:\/\/coolcasc.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/COOLCASC\/","https:\/\/x.com\/coolcasc","https:\/\/www.instagram.com\/coolcasc\/"]}]}},"_links":{"self":[{"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product\/22535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/comments?post=22535"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/media\/22495"}],"wp:attachment":[{"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/media?parent=22535"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product_brand?post=22535"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product_cat?post=22535"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product_tag?post=22535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}