{"id":8736,"date":"2018-11-18T23:30:54","date_gmt":"2018-11-18T23:30:54","guid":{"rendered":"http:\/\/coolcasc.com\/funda-para-casco\/led-monstre\/"},"modified":"2025-11-29T14:35:49","modified_gmt":"2025-11-29T14:35:49","slug":"led-monstre","status":"publish","type":"product","link":"https:\/\/coolcasc.com\/fr\/Housses de casque\/led-monstre\/","title":{"rendered":"Led Monstre"},"content":{"rendered":"<div class=\"row row-collapse row-full-width\"  id=\"row-2120321773\">\n\n\t<div id=\"col-615202541\" class=\"col medium-6 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center dark\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1236997593\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:0px 10px 0px 10px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"505\" height=\"505\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Colecciones\/Leds\/Live\/Funda-casco-Led-Monstruo-snow.jpg\" class=\"attachment-original size-original\" alt=\"Funda casco Led Monstruo snow\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1236997593 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1326831639\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:0px 10px 0px 10px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"505\" height=\"505\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Colecciones\/Leds\/Live\/Funda-casco-Led-Monstruo-Bike.jpg\" class=\"attachment-original size-original\" alt=\"Funda casco Led Monstruo Bike\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1326831639 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-69855869\" class=\"col medium-6 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1914222240\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:0px 10px 0px 10px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"505\" height=\"505\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Colecciones\/Leds\/Live\/Funda-casco-Led-Monstruo-Ski-1.jpg\" class=\"attachment-original size-original\" alt=\"Funda casco Led Monstruo Ski-1\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1914222240 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1715871023\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:0px 10px 0px 10px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"505\" height=\"505\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Colecciones\/Leds\/Live\/Funda-casco-Led-Monstruo-patinete.jpg\" class=\"attachment-original size-original\" alt=\"Funda casco Led Monstruo patinete\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1715871023 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-2120321773 > .col > .col-inner {\n  padding: 0px 0px 10px 0px;\n}\n<\/style>\n<\/div>\n<div class=\"container section-title-container\" style=\"margin-bottom:0px;\"><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" style=\"font-size:92%;\">POURQUOI METTRE UN COOLCASC \u00c0 MON CASQUE?<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n<div class=\"row row-small\"  id=\"row-1548619532\">\n\n\t<div id=\"col-1371371543\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<ul>\n<li style=\"text-align: left;\">Parce que je peux rapidement renouveler l&rsquo;aspect de mon casque..<\/li>\n<li style=\"text-align: left;\">Parce que je change de style quand je veux.<\/li>\n<li style=\"text-align: left;\">Parce qu&rsquo;il me pla\u00eet de diff\u00e9rer du reste.<\/li>\n<li style=\"text-align: left;\">Parce que je prot\u00e8ge mon casque des rayures.<\/li>\n<\/ul>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1371371543 > .col-inner {\n  margin: -35px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1207407713\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1418452954\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:-5px 0px 0px 0px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Colecciones\/Leds\/Funda-casco-Led-Monstruo-tercio.jpg\" class=\"attachment-original size-original\" alt=\"Funda casco Led Monstruo tercio\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1418452954 {\n  width: 80%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1207407713 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 0px 0px -17px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-104354420\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<ul>\n<li style=\"text-align: left;\">Parce que je peux l\u00b4utiliser toute l&rsquo;ann\u00e9e, pour n&rsquo;importe quel casque et dans n&rsquo;importe quel sport.<\/li>\n<li style=\"text-align: left;\">Parce qu&rsquo;il me pla\u00eet de mettre une touche de couleur et d&rsquo;humour\u00a0 \u00e0 ma vie.<\/li>\n<li style=\"text-align: left;\">Parce qu&rsquo;\u00e0 je suis plus visible donc je vais beaucoup plus s\u00fbr.<\/li>\n<\/ul>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-104354420 > .col-inner {\n  margin: -35px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-1548619532 > .col > .col-inner {\n  padding: 55px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n\n  <div class=\"banner has-hover\" id=\"banner-517755922\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"1050\" height=\"647\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Colecciones\/Leds\/Live\/Funda-casco-Led-Monstruo-Ski.jpg\" class=\"bg attachment-orginal size-orginal\" alt=\"Funda casco Led Monstruo ski\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1138221136\" class=\"text-box banner-layer x95 md-x95 lg-x95 y5 md-y5 lg-y5 res-text\">\n                                <div class=\"text-box-content text \">\n              \n              <div class=\"text-inner text-right\">\n                  \n<h2 class=\"uppercase\"><strong>Led Monstre<\/strong><\/h2>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1138221136 {\n  width: 60%;\n}\n#text-box-1138221136 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-1138221136 {\n    width: 29%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-517755922 {\n  padding-top: 61%;\n}\n#banner-517755922 .banner-bg img {\n  object-position: 56% 89%;\n}\n<\/style>\n  <\/div>\n\n\n<div class=\"row\"  id=\"row-2117442541\">\n\n\t<div id=\"col-1830877947\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container\" style=\"margin-bottom:0px;\"><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" style=\"font-size:92%;\">PACKAGING<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n<p>Le produit vient dans un blister personnalis\u00e9 de Led Monstre, avec images du casque avec la housse de Led Monstre et les instructions d&rsquo;usage.<\/p>\n<p>Le design et finition du blister changent chaque COOLCASC en cadeau original et excellent.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1454300330\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container\" style=\"margin-bottom:0px;\"><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" style=\"font-size:96%;\">ENTRETIEN ET LAVAGE<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n<p>Un produit fabriqu\u00e9 dans lycra \u00ae<\/p>\n<p><strong>Ne pas laver. <\/strong><\/p>\n<p><strong>La partie \u00e9lectrique serait endommag\u00e9e.<\/strong><\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-254860257\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container\" style=\"margin-bottom:0px;\"><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" style=\"font-size:96%;\">QUALITY<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n<p>Nos produits ont un design tr\u00e9s soign\u00e9 \u00a0et sont fabriqu\u00e9s par des mati\u00e8res premi\u00e8res de la plus haute qualit\u00e9.<\/p>\n<p>Tous les produits COOLCASC \u00ae r\u00e9visent manuellement et individuellement en suivant un protocole strict de contr\u00f4le de qualit\u00e9.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p class=\"productDescription\">Amusant monstre \u00e0 quatre yeux avec des lumi\u00e8res LED de diff\u00e9rentes couleurs.<\/p>\n<p class=\"productDescription\">Amusez-vous et effrayez tout le monde!<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Mat\u00e9riel:<\/strong> 83% Polyamide y 17% Elast\u00e1n.<\/p>\n<p><strong>Taille unique: <\/strong> s&rsquo;adapte \u00e0 n&rsquo;importe quelle taille de casque.<\/p>\n<p><strong>Multisport:<\/strong> Apte aux casques de ski, de bicyclette, trottinette, patinage, skate et m\u00eame moto.<\/p>\n<p><strong>Adaptable<\/strong> aux casques d&rsquo;oreillette molle. Une ouverture post\u00e9rieure pour fixer les lunettes dans des casques de ski.<\/p>\n<p><strong>Ne pas laver. La partie \u00e9lectrique serait endommag\u00e9e.<\/strong><\/p>\n","protected":false},"featured_media":5316,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[103],"product_tag":[211,225,127,139],"class_list":{"0":"post-8736","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-leds-fr","7":"product_tag-bleu","8":"product_tag-etui","9":"product_tag-leds-fr","10":"product_tag-les-couleurs","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Couvre casque Led Monstre - Coolcasc<\/title>\n<meta name=\"description\" content=\"\u00c9tui de notre dr\u00f4le monstre \u00e0 4 yeux, avec des lumi\u00e8res led de diff\u00e9rentes couleurs. Convient \u00e0 tous les casques. Covre casque Led Monstre.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coolcasc.com\/fr\/funda-para-casco\/led-monstre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Couvre casque Led Monstre - Coolcasc\" \/>\n<meta property=\"og:description\" content=\"\u00c9tui de notre dr\u00f4le monstre \u00e0 4 yeux, avec des lumi\u00e8res led de diff\u00e9rentes couleurs. Convient \u00e0 tous les casques. Covre casque Led Monstre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coolcasc.com\/fr\/funda-para-casco\/led-monstre\/\" \/>\n<meta property=\"og:site_name\" content=\"Coolcasc\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/COOLCASC\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-29T14:35:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Colecciones\/Leds\/Funda-casco-Led-Monstruo-Frontal.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@coolcasc\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/funda-para-casco\\\/led-monstre\\\/\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/funda-para-casco\\\/led-monstre\\\/\",\"name\":\"Couvre casque Led Monstre - Coolcasc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/funda-para-casco\\\/led-monstre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/funda-para-casco\\\/led-monstre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/Colecciones\\\/Leds\\\/Funda-casco-Led-Monstruo-Frontal.jpg\",\"datePublished\":\"2018-11-18T23:30:54+00:00\",\"dateModified\":\"2025-11-29T14:35:49+00:00\",\"description\":\"\u00c9tui de notre dr\u00f4le monstre \u00e0 4 yeux, avec des lumi\u00e8res led de diff\u00e9rentes couleurs. Convient \u00e0 tous les casques. Covre casque Led Monstre.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/funda-para-casco\\\/led-monstre\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/coolcasc.com\\\/fr\\\/funda-para-casco\\\/led-monstre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/funda-para-casco\\\/led-monstre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/Colecciones\\\/Leds\\\/Funda-casco-Led-Monstruo-Frontal.jpg\",\"contentUrl\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/Colecciones\\\/Leds\\\/Funda-casco-Led-Monstruo-Frontal.jpg\",\"width\":500,\"height\":500,\"caption\":\"Funda casco Led Monstruo Frontal\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/funda-para-casco\\\/led-monstre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Led Monstre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#website\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/\",\"name\":\"Coolcasc\",\"description\":\"Seguridad, moda y dise\u00f1o utilizando las fundas para casco Coolcasc en la pr\u00e1ctica de cualquier deporte.\",\"publisher\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/coolcasc.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#organization\",\"name\":\"Fundas para cascos Coolcasc\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Blue_header.png\",\"contentUrl\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Blue_header.png\",\"width\":300,\"height\":180,\"caption\":\"Fundas para cascos Coolcasc\"},\"image\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/COOLCASC\\\/\",\"https:\\\/\\\/x.com\\\/coolcasc\",\"https:\\\/\\\/www.instagram.com\\\/coolcasc\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Couvre casque Led Monstre - Coolcasc","description":"\u00c9tui de notre dr\u00f4le monstre \u00e0 4 yeux, avec des lumi\u00e8res led de diff\u00e9rentes couleurs. Convient \u00e0 tous les casques. Covre casque Led Monstre.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coolcasc.com\/fr\/funda-para-casco\/led-monstre\/","og_locale":"fr_FR","og_type":"article","og_title":"Couvre casque Led Monstre - Coolcasc","og_description":"\u00c9tui de notre dr\u00f4le monstre \u00e0 4 yeux, avec des lumi\u00e8res led de diff\u00e9rentes couleurs. Convient \u00e0 tous les casques. Covre casque Led Monstre.","og_url":"https:\/\/coolcasc.com\/fr\/funda-para-casco\/led-monstre\/","og_site_name":"Coolcasc","article_publisher":"https:\/\/www.facebook.com\/COOLCASC\/","article_modified_time":"2025-11-29T14:35:49+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/coolcasc.com\/wp-content\/uploads\/Colecciones\/Leds\/Funda-casco-Led-Monstruo-Frontal.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@coolcasc","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coolcasc.com\/fr\/funda-para-casco\/led-monstre\/","url":"https:\/\/coolcasc.com\/fr\/funda-para-casco\/led-monstre\/","name":"Couvre casque Led Monstre - Coolcasc","isPartOf":{"@id":"https:\/\/coolcasc.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/coolcasc.com\/fr\/funda-para-casco\/led-monstre\/#primaryimage"},"image":{"@id":"https:\/\/coolcasc.com\/fr\/funda-para-casco\/led-monstre\/#primaryimage"},"thumbnailUrl":"https:\/\/coolcasc.com\/wp-content\/uploads\/Colecciones\/Leds\/Funda-casco-Led-Monstruo-Frontal.jpg","datePublished":"2018-11-18T23:30:54+00:00","dateModified":"2025-11-29T14:35:49+00:00","description":"\u00c9tui de notre dr\u00f4le monstre \u00e0 4 yeux, avec des lumi\u00e8res led de diff\u00e9rentes couleurs. Convient \u00e0 tous les casques. Covre casque Led Monstre.","breadcrumb":{"@id":"https:\/\/coolcasc.com\/fr\/funda-para-casco\/led-monstre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coolcasc.com\/fr\/funda-para-casco\/led-monstre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/coolcasc.com\/fr\/funda-para-casco\/led-monstre\/#primaryimage","url":"https:\/\/coolcasc.com\/wp-content\/uploads\/Colecciones\/Leds\/Funda-casco-Led-Monstruo-Frontal.jpg","contentUrl":"https:\/\/coolcasc.com\/wp-content\/uploads\/Colecciones\/Leds\/Funda-casco-Led-Monstruo-Frontal.jpg","width":500,"height":500,"caption":"Funda casco Led Monstruo Frontal"},{"@type":"BreadcrumbList","@id":"https:\/\/coolcasc.com\/fr\/funda-para-casco\/led-monstre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/coolcasc.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/coolcasc.com\/fr\/tienda\/"},{"@type":"ListItem","position":3,"name":"Led Monstre"}]},{"@type":"WebSite","@id":"https:\/\/coolcasc.com\/#website","url":"https:\/\/coolcasc.com\/","name":"Coolcasc","description":"Seguridad, moda y dise\u00f1o utilizando las fundas para casco Coolcasc en la pr\u00e1ctica de cualquier deporte.","publisher":{"@id":"https:\/\/coolcasc.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coolcasc.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/coolcasc.com\/#organization","name":"Fundas para cascos Coolcasc","url":"https:\/\/coolcasc.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/coolcasc.com\/#\/schema\/logo\/image\/","url":"https:\/\/coolcasc.com\/wp-content\/uploads\/2018\/12\/Blue_header.png","contentUrl":"https:\/\/coolcasc.com\/wp-content\/uploads\/2018\/12\/Blue_header.png","width":300,"height":180,"caption":"Fundas para cascos Coolcasc"},"image":{"@id":"https:\/\/coolcasc.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/COOLCASC\/","https:\/\/x.com\/coolcasc","https:\/\/www.instagram.com\/coolcasc\/"]}]}},"_links":{"self":[{"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product\/8736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/comments?post=8736"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/media\/5316"}],"wp:attachment":[{"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/media?parent=8736"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product_brand?post=8736"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product_cat?post=8736"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product_tag?post=8736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}