{"id":8790,"date":"2018-11-14T18:25:08","date_gmt":"2018-11-14T18:25:08","guid":{"rendered":"http:\/\/coolcasc.com\/funda-para-casco\/eclair\/"},"modified":"2025-12-17T18:49:51","modified_gmt":"2025-12-17T18:49:51","slug":"eclair","status":"publish","type":"product","link":"https:\/\/coolcasc.com\/fr\/Housses de casque\/eclair\/","title":{"rendered":"\u00c9clair"},"content":{"rendered":"<div class=\"row\"  id=\"row-1835246334\">\n\n\t<div id=\"col-1149257184\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner dark\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1547722041\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:0px 10px 0px 10px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"505\" height=\"505\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Colecciones\/CoolPrint\/Live\/Funda-casco-Rayo.jpg\" class=\"attachment-original size-original\" alt=\"Funda casco Rayo\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1547722041 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-803432313\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_855897830\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:0px 10px 0px 10px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"505\" height=\"505\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Colecciones\/CoolPrint\/Live\/Funda-casco-Rayo-ski.jpg\" class=\"attachment-original size-original\" alt=\"Funda casco Rayo ski\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_855897830 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-1835246334 > .col > .col-inner {\n  padding: 33px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n<div class=\"container section-title-container\" style=\"margin-bottom:0px;\"><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" style=\"font-size:92%;\">POURQUOI METTRE UN COOLCASC \u00c0 MON CASQUE?<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n<div class=\"row row-small\"  id=\"row-1756864555\">\n\n\t<div id=\"col-765263198\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<ul>\n<li style=\"text-align: left;\">Parce que je peux rapidement renouveler l&rsquo;aspect de mon casque..<\/li>\n<li style=\"text-align: left;\">Parce que je change de style quand je veux.<\/li>\n<li style=\"text-align: left;\">Parce qu&rsquo;il me pla\u00eet de diff\u00e9rer du reste.<\/li>\n<li style=\"text-align: left;\">Parce que je prot\u00e8ge mon casque des rayures.<\/li>\n<\/ul>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-765263198 > .col-inner {\n  margin: -35px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-672895523\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2037423149\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:-5px 0px 0px 0px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Colecciones\/CoolPrint\/Funda_casco_Rayo.jpg\" class=\"attachment-original size-original\" alt=\"Funda casco Rayo\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2037423149 {\n  width: 80%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-672895523 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 0px 0px -17px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1432610316\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<ul>\n<li style=\"text-align: left;\">Parce que je peux l\u00b4utiliser toute l&rsquo;ann\u00e9e, pour n&rsquo;importe quel casque et dans n&rsquo;importe quel sport.<\/li>\n<li style=\"text-align: left;\">Parce qu&rsquo;il me pla\u00eet de mettre une touche de couleur et d&rsquo;humour\u00a0 \u00e0 ma vie.<\/li>\n<li style=\"text-align: left;\">Parce qu&rsquo;\u00e0 je suis plus visible donc je vais beaucoup plus s\u00fbr.<\/li>\n<\/ul>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1432610316 > .col-inner {\n  margin: -35px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-1756864555 > .col > .col-inner {\n  padding: 55px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n<div class=\"row\"  id=\"row-1341360230\">\n\n\t<div id=\"col-1218481067\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container\" style=\"margin-bottom:0px;\"><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" style=\"font-size:92%;\">PACKAGING<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n<p>Le produit vient dans un blister personnalis\u00e9 de Eclair, avec images du casque avec la housse de Eclair et les instructions d&rsquo;usage.<\/p>\n<p>Le design et finition du blister changent chaque COOLCASC en cadeau original et excellent.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1961009331\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container\" style=\"margin-bottom:0px;\"><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" style=\"font-size:96%;\">ENTRETIEN ET LAVAGE<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n<p>Un produit fabriqu\u00e9 dans lycra \u00ae<br \/>\nLaver un maximum \u00e0 30 \u00ba Celsius (65-85 F)<br \/>\nPas traitement d&rsquo;eau de Javel<br \/>\nS\u00e9chage en machine interdit<br \/>\nRepassage interdit.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-860370081\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container\" style=\"margin-bottom:0px;\"><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" style=\"font-size:96%;\">QUALITY<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n<p>Nos produits ont un design tr\u00e9s soign\u00e9 \u00a0et sont fabriqu\u00e9s par des mati\u00e8res premi\u00e8res de la plus haute qualit\u00e9.<\/p>\n<p>Tous les produits COOLCASC \u00ae r\u00e9visent manuellement et individuellement en suivant un protocole strict de contr\u00f4le de qualit\u00e9.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p class=\"productDescription\">Si vous \u00eates rapide comme l\u00b4\u00e9clair, ce couvre-casque est fait pour vous!<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Mat\u00e9riel:<\/strong> 83% Polyamide y 17% Elast\u00e1n.<\/p>\n<p><strong>Taille unique: <\/strong> s&rsquo;adapte \u00e0 n&rsquo;importe quelle taille de casque.<\/p>\n<p><strong>Multisport:<\/strong> Apte aux casques de ski, de bicyclette, trottinette, patinage, skate et m\u00eame moto.<\/p>\n<p><strong>Adaptable<\/strong> aux casques d&rsquo;oreillette molle. Une ouverture post\u00e9rieure pour fixer les lunettes dans des casques de ski.<\/p>\n","protected":false},"featured_media":5824,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[89],"product_tag":[217,211,135,119,225],"class_list":{"0":"post-8790","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cool-print-fr","7":"product_tag-blanc","8":"product_tag-bleu","9":"product_tag-casque","10":"product_tag-cool-print-fr","11":"product_tag-etui","13":"first","14":"instock","15":"sale","16":"taxable","17":"shipping-taxable","18":"purchasable","19":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Couvre casque \u00c9clair - Coolcasc<\/title>\n<meta name=\"description\" content=\"Si vous \u00eates rapide comme l&#039;\u00e9clair ... C&#039;est le cas de votre couvre casque! Elev\u00e9 en lycra stretch de la plus haute qualit\u00e9 avec une taille universelle pour tous les casques.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coolcasc.com\/fr\/funda-para-casco\/eclair\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Couvre casque \u00c9clair - Coolcasc\" \/>\n<meta property=\"og:description\" content=\"Si vous \u00eates rapide comme l&#039;\u00e9clair ... C&#039;est le cas de votre couvre casque! Elev\u00e9 en lycra stretch de la plus haute qualit\u00e9 avec une taille universelle pour tous les casques.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coolcasc.com\/fr\/funda-para-casco\/eclair\/\" \/>\n<meta property=\"og:site_name\" content=\"Coolcasc\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/COOLCASC\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-17T18:49:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Colecciones\/CoolPrint\/Funda_casco_Rayo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@coolcasc\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/funda-para-casco\\\/eclair\\\/\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/funda-para-casco\\\/eclair\\\/\",\"name\":\"Couvre casque \u00c9clair - Coolcasc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/funda-para-casco\\\/eclair\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/funda-para-casco\\\/eclair\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/Colecciones\\\/CoolPrint\\\/Funda_casco_Rayo.jpg\",\"datePublished\":\"2018-11-14T18:25:08+00:00\",\"dateModified\":\"2025-12-17T18:49:51+00:00\",\"description\":\"Si vous \u00eates rapide comme l'\u00e9clair ... C'est le cas de votre couvre casque! Elev\u00e9 en lycra stretch de la plus haute qualit\u00e9 avec une taille universelle pour tous les casques.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/funda-para-casco\\\/eclair\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/coolcasc.com\\\/fr\\\/funda-para-casco\\\/eclair\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/funda-para-casco\\\/eclair\\\/#primaryimage\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/Colecciones\\\/CoolPrint\\\/Funda_casco_Rayo.jpg\",\"contentUrl\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/Colecciones\\\/CoolPrint\\\/Funda_casco_Rayo.jpg\",\"width\":500,\"height\":500,\"caption\":\"Funda casco Rayo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/funda-para-casco\\\/eclair\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00c9clair\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#website\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/\",\"name\":\"Coolcasc\",\"description\":\"Seguridad, moda y dise\u00f1o utilizando las fundas para casco Coolcasc en la pr\u00e1ctica de cualquier deporte.\",\"publisher\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/coolcasc.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#organization\",\"name\":\"Fundas para cascos Coolcasc\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Blue_header.png\",\"contentUrl\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Blue_header.png\",\"width\":300,\"height\":180,\"caption\":\"Fundas para cascos Coolcasc\"},\"image\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/COOLCASC\\\/\",\"https:\\\/\\\/x.com\\\/coolcasc\",\"https:\\\/\\\/www.instagram.com\\\/coolcasc\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Couvre casque \u00c9clair - Coolcasc","description":"Si vous \u00eates rapide comme l'\u00e9clair ... C'est le cas de votre couvre casque! Elev\u00e9 en lycra stretch de la plus haute qualit\u00e9 avec une taille universelle pour tous les casques.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coolcasc.com\/fr\/funda-para-casco\/eclair\/","og_locale":"fr_FR","og_type":"article","og_title":"Couvre casque \u00c9clair - Coolcasc","og_description":"Si vous \u00eates rapide comme l'\u00e9clair ... C'est le cas de votre couvre casque! Elev\u00e9 en lycra stretch de la plus haute qualit\u00e9 avec une taille universelle pour tous les casques.","og_url":"https:\/\/coolcasc.com\/fr\/funda-para-casco\/eclair\/","og_site_name":"Coolcasc","article_publisher":"https:\/\/www.facebook.com\/COOLCASC\/","article_modified_time":"2025-12-17T18:49:51+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/coolcasc.com\/wp-content\/uploads\/Colecciones\/CoolPrint\/Funda_casco_Rayo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@coolcasc","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coolcasc.com\/fr\/funda-para-casco\/eclair\/","url":"https:\/\/coolcasc.com\/fr\/funda-para-casco\/eclair\/","name":"Couvre casque \u00c9clair - Coolcasc","isPartOf":{"@id":"https:\/\/coolcasc.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/coolcasc.com\/fr\/funda-para-casco\/eclair\/#primaryimage"},"image":{"@id":"https:\/\/coolcasc.com\/fr\/funda-para-casco\/eclair\/#primaryimage"},"thumbnailUrl":"https:\/\/coolcasc.com\/wp-content\/uploads\/Colecciones\/CoolPrint\/Funda_casco_Rayo.jpg","datePublished":"2018-11-14T18:25:08+00:00","dateModified":"2025-12-17T18:49:51+00:00","description":"Si vous \u00eates rapide comme l'\u00e9clair ... C'est le cas de votre couvre casque! Elev\u00e9 en lycra stretch de la plus haute qualit\u00e9 avec une taille universelle pour tous les casques.","breadcrumb":{"@id":"https:\/\/coolcasc.com\/fr\/funda-para-casco\/eclair\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coolcasc.com\/fr\/funda-para-casco\/eclair\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/coolcasc.com\/fr\/funda-para-casco\/eclair\/#primaryimage","url":"https:\/\/coolcasc.com\/wp-content\/uploads\/Colecciones\/CoolPrint\/Funda_casco_Rayo.jpg","contentUrl":"https:\/\/coolcasc.com\/wp-content\/uploads\/Colecciones\/CoolPrint\/Funda_casco_Rayo.jpg","width":500,"height":500,"caption":"Funda casco Rayo"},{"@type":"BreadcrumbList","@id":"https:\/\/coolcasc.com\/fr\/funda-para-casco\/eclair\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/coolcasc.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/coolcasc.com\/fr\/tienda\/"},{"@type":"ListItem","position":3,"name":"\u00c9clair"}]},{"@type":"WebSite","@id":"https:\/\/coolcasc.com\/#website","url":"https:\/\/coolcasc.com\/","name":"Coolcasc","description":"Seguridad, moda y dise\u00f1o utilizando las fundas para casco Coolcasc en la pr\u00e1ctica de cualquier deporte.","publisher":{"@id":"https:\/\/coolcasc.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coolcasc.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/coolcasc.com\/#organization","name":"Fundas para cascos Coolcasc","url":"https:\/\/coolcasc.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/coolcasc.com\/#\/schema\/logo\/image\/","url":"https:\/\/coolcasc.com\/wp-content\/uploads\/2018\/12\/Blue_header.png","contentUrl":"https:\/\/coolcasc.com\/wp-content\/uploads\/2018\/12\/Blue_header.png","width":300,"height":180,"caption":"Fundas para cascos Coolcasc"},"image":{"@id":"https:\/\/coolcasc.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/COOLCASC\/","https:\/\/x.com\/coolcasc","https:\/\/www.instagram.com\/coolcasc\/"]}]}},"_links":{"self":[{"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product\/8790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/comments?post=8790"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/media\/5824"}],"wp:attachment":[{"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/media?parent=8790"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product_brand?post=8790"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product_cat?post=8790"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product_tag?post=8790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}