{"id":430,"count":56,"description":"<h1>Housse pour masque de ski : Protection et style<\/h1>\r\nD\u00e9couvrez nos <strong>housses pour masques de ski COOLMASC<strong>, <\/strong><\/strong>con\u00e7ues avec les mat\u00e9riaux les plus innovants et durables.\r\n\r\nLes housses pour lunettes de ski COOLMASC sont l\u2019option parfaite pour ceux qui recherchent une protection simple avec une touche distinctive. Fabriqu\u00e9es en polyester recycl\u00e9 issu de bouteilles en plastique, nous garantissons durabilit\u00e9 et un ajustement parfait, car elles sont toujours en taille unique.\r\n\r\nExplorez notre vari\u00e9t\u00e9 de <strong>housses pour lunettes<strong> et trouvez l\u2019accessoire id\u00e9al pour votre \u00e9quipement de ski en l\u2019associant \u00e0 votre housse de casque.\r\n<\/strong><\/strong>D\u00e9marquez-vous sur les pistes avec des housses pour lunettes qui marquent la tendance !","link":"https:\/\/coolcasc.com\/fr\/fundas-casco\/couvre-masques-coolmasc\/rpet-fr\/","name":"RPET","slug":"rpet-fr","taxonomy":"product_cat","parent":271,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RPET archivos - Coolcasc<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coolcasc.com\/fr\/fundas-casco\/couvre-masques-coolmasc\/rpet-fr\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RPET archivos - Coolcasc\" \/>\n<meta property=\"og:description\" content=\"Housse pour masque de ski : Protection et style D\u00e9couvrez nos housses pour masques de ski COOLMASC, con\u00e7ues avec les mat\u00e9riaux les plus innovants et durables. Les housses pour lunettes de ski COOLMASC sont l\u2019option parfaite pour ceux qui recherchent une protection simple avec une touche distinctive. Fabriqu\u00e9es en polyester recycl\u00e9 issu de bouteilles en plastique, nous garantissons durabilit\u00e9 et un ajustement parfait, car elles sont toujours en taille unique. Explorez notre vari\u00e9t\u00e9 de housses pour lunettes et trouvez l\u2019accessoire id\u00e9al pour votre \u00e9quipement de ski en l\u2019associant \u00e0 votre housse de casque. D\u00e9marquez-vous sur les pistes avec des housses pour lunettes qui marquent la tendance !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coolcasc.com\/fr\/fundas-casco\/couvre-masques-coolmasc\/rpet-fr\/\" \/>\n<meta property=\"og:site_name\" content=\"Coolcasc\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@coolcasc\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/fundas-casco\\\/couvre-masques-coolmasc\\\/rpet-fr\\\/\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/fundas-casco\\\/couvre-masques-coolmasc\\\/rpet-fr\\\/\",\"name\":\"RPET archivos - Coolcasc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/fundas-casco\\\/couvre-masques-coolmasc\\\/rpet-fr\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/fundas-casco\\\/couvre-masques-coolmasc\\\/rpet-fr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Couvre masques Coolmasc\",\"item\":\"https:\\\/\\\/coolcasc.com\\\/fr\\\/fundas-casco\\\/couvre-masques-coolmasc\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"RPET\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#website\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/\",\"name\":\"Coolcasc\",\"description\":\"Seguridad, moda y dise\u00f1o utilizando las fundas para casco Coolcasc en la pr\u00e1ctica de cualquier deporte.\",\"publisher\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/coolcasc.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#organization\",\"name\":\"Fundas para cascos Coolcasc\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Blue_header.png\",\"contentUrl\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Blue_header.png\",\"width\":300,\"height\":180,\"caption\":\"Fundas para cascos Coolcasc\"},\"image\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/COOLCASC\\\/\",\"https:\\\/\\\/x.com\\\/coolcasc\",\"https:\\\/\\\/www.instagram.com\\\/coolcasc\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RPET archivos - Coolcasc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coolcasc.com\/fr\/fundas-casco\/couvre-masques-coolmasc\/rpet-fr\/","og_locale":"fr_FR","og_type":"article","og_title":"RPET archivos - Coolcasc","og_description":"Housse pour masque de ski : Protection et style D\u00e9couvrez nos housses pour masques de ski COOLMASC, con\u00e7ues avec les mat\u00e9riaux les plus innovants et durables. Les housses pour lunettes de ski COOLMASC sont l\u2019option parfaite pour ceux qui recherchent une protection simple avec une touche distinctive. Fabriqu\u00e9es en polyester recycl\u00e9 issu de bouteilles en plastique, nous garantissons durabilit\u00e9 et un ajustement parfait, car elles sont toujours en taille unique. Explorez notre vari\u00e9t\u00e9 de housses pour lunettes et trouvez l\u2019accessoire id\u00e9al pour votre \u00e9quipement de ski en l\u2019associant \u00e0 votre housse de casque. D\u00e9marquez-vous sur les pistes avec des housses pour lunettes qui marquent la tendance !","og_url":"https:\/\/coolcasc.com\/fr\/fundas-casco\/couvre-masques-coolmasc\/rpet-fr\/","og_site_name":"Coolcasc","twitter_card":"summary_large_image","twitter_site":"@coolcasc","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/coolcasc.com\/fr\/fundas-casco\/couvre-masques-coolmasc\/rpet-fr\/","url":"https:\/\/coolcasc.com\/fr\/fundas-casco\/couvre-masques-coolmasc\/rpet-fr\/","name":"RPET archivos - Coolcasc","isPartOf":{"@id":"https:\/\/coolcasc.com\/#website"},"breadcrumb":{"@id":"https:\/\/coolcasc.com\/fr\/fundas-casco\/couvre-masques-coolmasc\/rpet-fr\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/coolcasc.com\/fr\/fundas-casco\/couvre-masques-coolmasc\/rpet-fr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/coolcasc.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Couvre masques Coolmasc","item":"https:\/\/coolcasc.com\/fr\/fundas-casco\/couvre-masques-coolmasc\/"},{"@type":"ListItem","position":3,"name":"RPET"}]},{"@type":"WebSite","@id":"https:\/\/coolcasc.com\/#website","url":"https:\/\/coolcasc.com\/","name":"Coolcasc","description":"Seguridad, moda y dise\u00f1o utilizando las fundas para casco Coolcasc en la pr\u00e1ctica de cualquier deporte.","publisher":{"@id":"https:\/\/coolcasc.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coolcasc.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/coolcasc.com\/#organization","name":"Fundas para cascos Coolcasc","url":"https:\/\/coolcasc.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/coolcasc.com\/#\/schema\/logo\/image\/","url":"https:\/\/coolcasc.com\/wp-content\/uploads\/2018\/12\/Blue_header.png","contentUrl":"https:\/\/coolcasc.com\/wp-content\/uploads\/2018\/12\/Blue_header.png","width":300,"height":180,"caption":"Fundas para cascos Coolcasc"},"image":{"@id":"https:\/\/coolcasc.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/COOLCASC\/","https:\/\/x.com\/coolcasc","https:\/\/www.instagram.com\/coolcasc\/"]}]}},"_links":{"self":[{"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product_cat\/430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product_cat\/271"}],"wp:post_type":[{"href":"https:\/\/coolcasc.com\/fr\/wp-json\/wp\/v2\/product?product_cat=430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}