{"id":6329,"date":"2019-01-31T01:48:56","date_gmt":"2019-01-31T01:48:56","guid":{"rendered":"http:\/\/coolcasc.com\/?page_id=6329"},"modified":"2019-02-01T13:39:17","modified_gmt":"2019-02-01T13:39:17","slug":"jet-b","status":"publish","type":"page","link":"https:\/\/coolcasc.com\/it\/personalizzato\/jet-b\/","title":{"rendered":"Jet B"},"content":{"rendered":"\n<div class=\"row align-center\"  id=\"row-493461077\">\n\n\n\t<div id=\"col-1231368341\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"height:10px;\"><\/div><\/div>\n\n<div style=\"text-align: justify;\">\n<p style=\"text-align: center;\">Collezione di fodere per caschi, ideata per una customizzazione al 100%, a un prezzo pi\u00f9 conveniente. Resistenti e riutilizzabili per almeno 5 stagioni. Realizzate in Lycra a uno strato, con rifinitura lucida.<\/p>\n<p style=\"text-align: center;\">Anche questa collezione si adatta a ogni casco, per qualsiasi sport, in modo che la stessa fodera avr\u00e0 molteplici usi: sci, ciclismo, hockey, pattinaggio. <\/p>\n<\/div>\n<div class=\"row align-center\"  id=\"row-1109782667\">\n\n\n\t<div id=\"col-1830210273\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1067429318\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Customizados\/JetB\/Funda-casco-JetB_03.jpg\" class=\"attachment-original size-original\" alt=\"funda customizada Jet B 03\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1067429318 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2019926589\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1966616755\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Customizados\/JetB\/Funda-casco-JetB_02.jpg\" class=\"attachment-original size-original\" alt=\"funda customizada Jet B 02\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1966616755 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-731274021\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_588009946\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Customizados\/JetB\/Funda-casco-JetB_07.jpg\" class=\"attachment-original size-original\" alt=\"funda customizada Jet B 07\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_588009946 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1241347389\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1280723209\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Customizados\/JetB\/Funda-casco-Jet-B-08.jpg\" class=\"attachment-original size-original\" alt=\"funda customizada Jet B 08\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1280723209 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row align-center\"  id=\"row-259719215\">\n\n\n\t<div id=\"col-1329610120\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_281562870\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Customizados\/JetB\/Funda-casco-JetB_06.jpg\" class=\"attachment-original size-original\" alt=\"funda customizada Jet B 06\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_281562870 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1770367450\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1207244422\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Customizados\/JetB\/Funda-casco-JetB_01.jpg\" class=\"attachment-original size-original\" alt=\"funda customizada Jet B 01\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1207244422 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1978680708\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_201186891\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Customizados\/JetB\/Funda-casco-JetB_05.jpg\" class=\"attachment-original size-original\" alt=\"funda customizada Jet B 05\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_201186891 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-864038106\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1667274992\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Customizados\/JetB\/Funda-casco-JetB_04.jpg\" class=\"attachment-original size-original\" alt=\"funda customizada Jet B 04\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1667274992 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div style=\"text-align: justify;\">\n<p style=\"text-align: center;\">Potrai usare la stessa fodera, a parit\u00e0 d\u2019investimento, in vari modi e potrai personalizzare diverse attrezzature sportive di uno stesso circolo o di una stessa scuola.<\/p>\n<p style=\"text-align: center;\">Jet B \u00e8 un supporto rivoluzionario per la pubblicit\u00e0 o il merchandising.<\/p>\n<\/div>\n<div style=\"text-align: justify;\">\n<p style=\"text-align: center;\">Quale forma migliore di pubblicit\u00e0 o di marketing se non vedere la tua marca su centinaia di persone che si spostano e si muovono in una corsa o in un evento sportivo?<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<div class=\"row align-center\"  id=\"row-1555685871\">\n\n\n\t<div id=\"col-930229966\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_716874750\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"315\" height=\"315\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Customizados\/JetB\/funda-customizada-Jet-B-4.jpg\" class=\"attachment-original size-original\" alt=\"funda customizada Jet B 4\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_716874750 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1190663099\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"315\" height=\"315\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Customizados\/JetB\/funda-customizada-Jet-B.jpg\" class=\"attachment-original size-original\" alt=\"funda customizada Jet B\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1190663099 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1221646332\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_812668643\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"315\" height=\"315\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Customizados\/JetB\/funda-customizada-Jet-B-3.jpg\" class=\"attachment-original size-original\" alt=\"funda customizada Jet B 3\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_812668643 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_787539210\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"315\" height=\"315\" src=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Customizados\/JetB\/funda-customizada-Jet-B-2.jpg\" class=\"attachment-original size-original\" alt=\"funda customizada Jet B 2\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_787539210 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":6079,"parent":3780,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank-featured.php","meta":{"footnotes":""},"class_list":["post-6329","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fundas para casco customizadas modelo Jet B - Coolcasc<\/title>\n<meta name=\"description\" content=\"Colecci\u00f3n de fundas para casco, ideada para una customizaci\u00f3n 100%, a un precio m\u00e1s econ\u00f3mico. Muy resistentes y totalmente reutilizables.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coolcasc.com\/it\/personalizzato\/jet-b\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fundas para casco customizadas modelo Jet B - Coolcasc\" \/>\n<meta property=\"og:description\" content=\"Colecci\u00f3n de fundas para casco, ideada para una customizaci\u00f3n 100%, a un precio m\u00e1s econ\u00f3mico. Muy resistentes y totalmente reutilizables.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coolcasc.com\/it\/personalizzato\/jet-b\/\" \/>\n<meta property=\"og:site_name\" content=\"Coolcasc\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/COOLCASC\/\" \/>\n<meta property=\"article:modified_time\" content=\"2019-02-01T13:39:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coolcasc.com\/wp-content\/uploads\/Paginas\/banner-customizados-Jet-B.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@coolcasc\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/it\\\/personalizzato\\\/jet-b\\\/\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/it\\\/personalizzato\\\/jet-b\\\/\",\"name\":\"Fundas para casco customizadas modelo Jet B - Coolcasc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/it\\\/personalizzato\\\/jet-b\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/it\\\/personalizzato\\\/jet-b\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/Paginas\\\/banner-customizados-Jet-B.jpg\",\"datePublished\":\"2019-01-31T01:48:56+00:00\",\"dateModified\":\"2019-02-01T13:39:17+00:00\",\"description\":\"Colecci\u00f3n de fundas para casco, ideada para una customizaci\u00f3n 100%, a un precio m\u00e1s econ\u00f3mico. Muy resistentes y totalmente reutilizables.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/it\\\/personalizzato\\\/jet-b\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/coolcasc.com\\\/it\\\/personalizzato\\\/jet-b\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/it\\\/personalizzato\\\/jet-b\\\/#primaryimage\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/Paginas\\\/banner-customizados-Jet-B.jpg\",\"contentUrl\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/Paginas\\\/banner-customizados-Jet-B.jpg\",\"width\":1400,\"height\":300,\"caption\":\"banner customizados Jet B\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/it\\\/personalizzato\\\/jet-b\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/coolcasc.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Personalizzato\",\"item\":\"https:\\\/\\\/coolcasc.com\\\/it\\\/personalizzato\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Jet B\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#website\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/\",\"name\":\"Coolcasc\",\"description\":\"Seguridad, moda y dise\u00f1o utilizando las fundas para casco Coolcasc en la pr\u00e1ctica de cualquier deporte.\",\"publisher\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/coolcasc.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#organization\",\"name\":\"Fundas para cascos Coolcasc\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Blue_header.png\",\"contentUrl\":\"https:\\\/\\\/coolcasc.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Blue_header.png\",\"width\":300,\"height\":180,\"caption\":\"Fundas para cascos Coolcasc\"},\"image\":{\"@id\":\"https:\\\/\\\/coolcasc.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/COOLCASC\\\/\",\"https:\\\/\\\/x.com\\\/coolcasc\",\"https:\\\/\\\/www.instagram.com\\\/coolcasc\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fundas para casco customizadas modelo Jet B - Coolcasc","description":"Colecci\u00f3n de fundas para casco, ideada para una customizaci\u00f3n 100%, a un precio m\u00e1s econ\u00f3mico. Muy resistentes y totalmente reutilizables.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coolcasc.com\/it\/personalizzato\/jet-b\/","og_locale":"it_IT","og_type":"article","og_title":"Fundas para casco customizadas modelo Jet B - Coolcasc","og_description":"Colecci\u00f3n de fundas para casco, ideada para una customizaci\u00f3n 100%, a un precio m\u00e1s econ\u00f3mico. Muy resistentes y totalmente reutilizables.","og_url":"https:\/\/coolcasc.com\/it\/personalizzato\/jet-b\/","og_site_name":"Coolcasc","article_publisher":"https:\/\/www.facebook.com\/COOLCASC\/","article_modified_time":"2019-02-01T13:39:17+00:00","og_image":[{"width":1400,"height":300,"url":"https:\/\/coolcasc.com\/wp-content\/uploads\/Paginas\/banner-customizados-Jet-B.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@coolcasc","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coolcasc.com\/it\/personalizzato\/jet-b\/","url":"https:\/\/coolcasc.com\/it\/personalizzato\/jet-b\/","name":"Fundas para casco customizadas modelo Jet B - Coolcasc","isPartOf":{"@id":"https:\/\/coolcasc.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/coolcasc.com\/it\/personalizzato\/jet-b\/#primaryimage"},"image":{"@id":"https:\/\/coolcasc.com\/it\/personalizzato\/jet-b\/#primaryimage"},"thumbnailUrl":"https:\/\/coolcasc.com\/wp-content\/uploads\/Paginas\/banner-customizados-Jet-B.jpg","datePublished":"2019-01-31T01:48:56+00:00","dateModified":"2019-02-01T13:39:17+00:00","description":"Colecci\u00f3n de fundas para casco, ideada para una customizaci\u00f3n 100%, a un precio m\u00e1s econ\u00f3mico. Muy resistentes y totalmente reutilizables.","breadcrumb":{"@id":"https:\/\/coolcasc.com\/it\/personalizzato\/jet-b\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coolcasc.com\/it\/personalizzato\/jet-b\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/coolcasc.com\/it\/personalizzato\/jet-b\/#primaryimage","url":"https:\/\/coolcasc.com\/wp-content\/uploads\/Paginas\/banner-customizados-Jet-B.jpg","contentUrl":"https:\/\/coolcasc.com\/wp-content\/uploads\/Paginas\/banner-customizados-Jet-B.jpg","width":1400,"height":300,"caption":"banner customizados Jet B"},{"@type":"BreadcrumbList","@id":"https:\/\/coolcasc.com\/it\/personalizzato\/jet-b\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/coolcasc.com\/it\/"},{"@type":"ListItem","position":2,"name":"Personalizzato","item":"https:\/\/coolcasc.com\/it\/personalizzato\/"},{"@type":"ListItem","position":3,"name":"Jet B"}]},{"@type":"WebSite","@id":"https:\/\/coolcasc.com\/#website","url":"https:\/\/coolcasc.com\/","name":"Coolcasc","description":"Seguridad, moda y dise\u00f1o utilizando las fundas para casco Coolcasc en la pr\u00e1ctica de cualquier deporte.","publisher":{"@id":"https:\/\/coolcasc.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coolcasc.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/coolcasc.com\/#organization","name":"Fundas para cascos Coolcasc","url":"https:\/\/coolcasc.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/coolcasc.com\/#\/schema\/logo\/image\/","url":"https:\/\/coolcasc.com\/wp-content\/uploads\/2018\/12\/Blue_header.png","contentUrl":"https:\/\/coolcasc.com\/wp-content\/uploads\/2018\/12\/Blue_header.png","width":300,"height":180,"caption":"Fundas para cascos Coolcasc"},"image":{"@id":"https:\/\/coolcasc.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/COOLCASC\/","https:\/\/x.com\/coolcasc","https:\/\/www.instagram.com\/coolcasc\/"]}]}},"_links":{"self":[{"href":"https:\/\/coolcasc.com\/it\/wp-json\/wp\/v2\/pages\/6329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coolcasc.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/coolcasc.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/coolcasc.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/coolcasc.com\/it\/wp-json\/wp\/v2\/comments?post=6329"}],"version-history":[{"count":0,"href":"https:\/\/coolcasc.com\/it\/wp-json\/wp\/v2\/pages\/6329\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/coolcasc.com\/it\/wp-json\/wp\/v2\/pages\/3780"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coolcasc.com\/it\/wp-json\/wp\/v2\/media\/6079"}],"wp:attachment":[{"href":"https:\/\/coolcasc.com\/it\/wp-json\/wp\/v2\/media?parent=6329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}